{"id":12015,"date":"2023-03-11T12:00:24","date_gmt":"2023-03-11T08:30:24","guid":{"rendered":"https:\/\/rahaco.net\/mag\/?p=12015"},"modified":"2023-07-17T14:38:33","modified_gmt":"2023-07-17T11:08:33","slug":"parallel-processing-application","status":"publish","type":"post","link":"https:\/\/rahaco.net\/mag\/parallel-processing-application\/","title":{"rendered":"\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc\u061b \u0628\u0647\u062a\u0631\u06cc\u0646 \u0631\u0648\u0634 \u0628\u0631\u0627\u06cc \u0627\u0646\u062c\u0627\u0645 \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u067e\u06cc\u0686\u06cc\u062f\u0647"},"content":{"rendered":"<p style=\"text-align: justify;\">\u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u0628\u0647 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0633\u0631\u0639\u062a \u0645\u062d\u0627\u0633\u0628\u0627\u062a\u06cc \u0648 \u062a\u0642\u0633\u06cc\u0645 \u0622\u0646 \u0628\u0647 \u06a9\u0627\u0631\u0647\u0627\u06cc \u06a9\u0648\u0686\u06a9\u200c\u062a\u0631 \u062f\u0631 \u0686\u0646\u062f\u06cc\u0646 \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647 \u0627\u0634\u0627\u0631\u0647 \u062f\u0627\u0631\u062f. \u0627\u06af\u0631 <a href=\"https:\/\/rahaco.net\/mag\/parallel-processing\/\">\u0645\u062d\u0627\u0633\u0628\u0627\u062a \u0645\u0648\u0627\u0632\u06cc<\/a> \u06cc\u06a9 \u062a\u0639\u0631\u06cc\u0641 \u06a9\u0644\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f\u060c \u0647\u0645\u06cc\u0646 &#8220;\u062a\u0642\u0633\u06cc\u0645 \u06a9\u0627\u0631&#8221; \u0627\u0633\u062a. \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u0627\u0632 \u0646\u0638\u0631 \u0645\u062d\u0627\u0633\u0628\u0627\u062a\u06cc \u0628\u0627\u0639\u062b \u0627\u06cc\u062c\u0627\u062f \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u0639\u0645\u06cc\u0642 \u062f\u0631 \u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u062f\u0627\u0631\u0648\u06cc\u06cc\u060c \u0627\u06a9\u062a\u0634\u0627\u0641 \u0627\u0646\u0631\u0698\u06cc\u060c \u062a\u0635\u0648\u06cc\u0631 \u0628\u0631\u062f\u0627\u0631\u06cc \u067e\u0632\u0634\u06a9\u06cc \u0648 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0645\u0648\u0627\u0631\u062f \u062f\u06cc\u06af\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0628\u0647 \u0646\u0645\u0648\u0646\u0647\u200c\u0627\u06cc \u0627\u0632 \u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u067e\u0631\u062f\u0627\u062e\u062a\u0647 \u0627\u06cc\u0645.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-white ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0622\u0646\u0686\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0646\u0648\u0634\u062a\u0647 \u0645\u06cc\u200c\u062e\u0648\u0627\u0646\u06cc\u062f:<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/rahaco.net\/mag\/parallel-processing-application\/#%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D9%85%D9%88%D8%A7%D8%B2%DB%8C_%D8%AF%D8%B1_%D8%AF%D9%86%DB%8C%D8%A7%DB%8C_%D8%AA%DA%A9%D9%86%D9%88%D9%84%D9%88%DA%98%DB%8C\" >\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u062f\u0646\u06cc\u0627\u06cc \u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/rahaco.net\/mag\/parallel-processing-application\/#%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D9%85%D9%88%D8%A7%D8%B2%DB%8C_%D8%AF%D8%B1_%D9%86%D8%AC%D9%88%D9%85\" >\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u0646\u062c\u0648\u0645<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/rahaco.net\/mag\/parallel-processing-application\/#%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D9%85%D9%88%D8%A7%D8%B2%DB%8C_%D8%AF%D8%B1_%DA%A9%D8%B4%D8%A7%D9%88%D8%B1%D8%B2%DB%8C\" >\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/rahaco.net\/mag\/parallel-processing-application\/#%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D9%85%D9%88%D8%A7%D8%B2%DB%8C_%D8%AF%D8%B1_%D8%A7%D9%82%D8%AA%D8%B5%D8%A7%D8%AF_%D8%AC%D8%A7%D9%85%D8%B9%D9%87\" >\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u0627\u0642\u062a\u0635\u0627\u062f \u062c\u0627\u0645\u0639\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/rahaco.net\/mag\/parallel-processing-application\/#%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D9%85%D9%88%D8%A7%D8%B2%DB%8C_%D8%AF%D8%B1_%D8%AA%D8%AC%D8%A7%D8%B1%D8%AA\" >\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u062a\u062c\u0627\u0631\u062a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/rahaco.net\/mag\/parallel-processing-application\/#%D9%86%D8%AD%D9%88%D9%87_%D8%A7%D8%B3%D8%AA%D9%81%D8%A7%D8%AF%D9%87_%D8%A7%D8%B2_%D9%85%D8%AD%D8%A7%D8%B3%D8%A8%D8%A7%D8%AA_%D9%85%D9%88%D8%A7%D8%B2%DB%8C_%D8%AF%D8%B1_%D8%AA%D8%AC%D8%A7%D8%B1%D8%AA\" >\u0646\u062d\u0648\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u062a\u062c\u0627\u0631\u062a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/rahaco.net\/mag\/parallel-processing-application\/#%D9%86%D8%AD%D9%88%D9%87_%D8%A7%D8%B3%D8%AA%D9%81%D8%A7%D8%AF%D9%87_%D8%A7%D8%B2_%D9%85%D8%AD%D8%A7%D8%B3%D8%A8%D8%A7%D8%AA_%D9%85%D9%88%D8%A7%D8%B2%DB%8C_%D8%AF%D8%B1_%D9%85%D8%B5%D8%B1%D9%81_%D8%A7%D9%86%D8%B1%DA%98%DB%8C\" >\u0646\u062d\u0648\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u0645\u0635\u0631\u0641 \u0627\u0646\u0631\u0698\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/rahaco.net\/mag\/parallel-processing-application\/#%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D9%85%D9%88%D8%A7%D8%B2%DB%8C_%D8%AF%D8%B1_%D9%BE%D8%B2%D8%B4%DA%A9%DB%8C_%D9%88_%DA%A9%D8%B4%D9%81_%D8%AF%D8%A7%D8%B1%D9%88\" >\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u067e\u0632\u0634\u06a9\u06cc \u0648 \u06a9\u0634\u0641 \u062f\u0627\u0631\u0648<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/rahaco.net\/mag\/parallel-processing-application\/#%D9%86%D8%AA%DB%8C%D8%AC%D9%87_%DA%AF%DB%8C%D8%B1%DB%8C\" >\u0646\u062a\u06cc\u062c\u0647 \u06af\u06cc\u0631\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/rahaco.net\/mag\/parallel-processing-application\/#%D8%AF%D8%A7%D9%86%D9%84%D9%88%D8%AF_PDF_%D9%85%D9%82%D8%A7%D9%84%D9%87_%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D9%85%D9%88%D8%A7%D8%B2%DB%8C\" >\u062f\u0627\u0646\u0644\u0648\u062f PDF \u0645\u0642\u0627\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D9%85%D9%88%D8%A7%D8%B2%DB%8C_%D8%AF%D8%B1_%D8%AF%D9%86%DB%8C%D8%A7%DB%8C_%D8%AA%DA%A9%D9%86%D9%88%D9%84%D9%88%DA%98%DB%8C\"><\/span><strong>\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u062f\u0646\u06cc\u0627\u06cc \u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">\u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u0645\u0648\u0627\u0632\u06cc \u0647\u0645 \u0634\u0646\u0627\u062e\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f. \u06a9\u0627\u0631\u0628\u0631\u062f\u0647\u0627\u06cc \u0627\u06cc\u0646 \u0641\u0646\u0627\u0648\u0631\u06cc \u0634\u0627\u0645\u0644: \u0627\u062e\u062a\u0631\u0634\u0646\u0627\u0633\u06cc\u060c \u0698\u0626\u0648 \u067e\u0631\u062f\u0627\u0632\u0634\u060c \u0645\u062f\u0644 \u0633\u0627\u0632\u06cc \u0622\u0628 \u0648 \u0647\u0648\u0627\u060c \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc\u060c \u0645\u062f\u06cc\u0631\u06cc\u062a \u0645\u0627\u0644\u06cc\u060c \u0627\u0635\u0644\u0627\u062d \u0631\u0646\u06af \u0648\u06cc\u062f\u0626\u0648\u060c \u062f\u06cc\u0646\u0627\u0645\u06cc\u06a9 \u0633\u06cc\u0627\u0644\u0627\u062a\u060c \u062a\u0635\u0648\u06cc\u0631 \u0628\u0631\u062f\u0627\u0631\u06cc \u067e\u0632\u0634\u06a9\u06cc \u0648 \u06a9\u0634\u0641 \u062f\u0627\u0631\u0648 \u0627\u0633\u062a. \u067e\u062f\u0631 \u0639\u0644\u0645 \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u0645\u0648\u0627\u0632\u06cc Huw \u0647\u0648\u0648 \u0645\u06cc\u200c\u06af\u0648\u06cc\u062f: \u0627\u06af\u0631 \u0628\u0647 \u062c\u0627\u0645\u0639\u0647 \u0639\u0644\u0645\u06cc \u0627\u0645\u0631\u0648\u0632 \u0646\u06af\u0627\u0647 \u06a9\u0646\u06cc\u062f\u060c \u0631\u0627\u06cc\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f \u0645\u0627\u0646\u0646\u062f: \u0627\u0628\u0631 \u06a9\u0627\u0645\u067e\u06cc\u0648\u062a\u0631\u200c\u0647\u0627\u06cc IBM Summit \u0648 Aurora \u0639\u0645\u062f\u062a\u0627 \u0628\u0631 \u0627\u0633\u0627\u0633 \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647\u200c\u0627\u0646\u062f. \u0627\u06cc\u0646 \u0645\u062f\u0644 \u062f\u0631 \u0635\u0646\u0627\u06cc\u0639 \u067e\u0632\u0634\u06a9\u06cc \u0648 \u062a\u062c\u0627\u0631\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f \u0628\u0633\u06cc\u0627\u0631\u06cc \u062f\u0627\u0631\u062f \u06a9\u0647 \u0647\u0645\u0647 \u0686\u06cc\u0632 \u0631\u0627 \u0627\u0632 \u06a9\u0634\u0641 \u062f\u0627\u0631\u0648 \u06af\u0631\u0641\u062a\u0647 \u062a\u0627 \u0634\u0628\u06cc\u0647\u200c \u0633\u0627\u0632\u06cc\u200c\u0647\u0627\u06cc \u0628\u06cc\u0646 \u0633\u062a\u0627\u0631\u0647\u200c\u0627\u06cc \u0648 \u062a\u06a9\u0646\u06cc\u06a9\u200c\u0647\u0627\u06cc \u0641\u06cc\u0644\u0645 \u067e\u0633 \u0627\u0632 \u062a\u0648\u0644\u06cc\u062f \u0631\u0627 \u062a\u0633\u0647\u06cc\u0644 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062f\u0631 \u0627\u06cc\u0646\u062c\u0627 \u0686\u0646\u062f \u0645\u0648\u0631\u062f \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f \u06a9\u0647 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u0645\u0648\u0627\u0632\u06cc \u0628\u0647 \u0628\u0647\u0628\u0648\u062f \u0646\u062a\u0627\u06cc\u062c \u0648 \u062d\u0644 \u0645\u0648\u0627\u0631\u062f \u063a\u06cc\u0631 \u0642\u0627\u0628\u0644 \u062d\u0644 \u0642\u0628\u0644\u06cc \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-12156\" src=\"https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/03\/\u067e\u0631\u062f\u0627\u0632\u0634-\u0645\u0648\u0627\u0632\u06cc-1.jpg\" alt=\"\u0645\u0632\u0627\u06cc\u0627\u06cc \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc\" width=\"700\" height=\"350\" srcset=\"https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/03\/\u067e\u0631\u062f\u0627\u0632\u0634-\u0645\u0648\u0627\u0632\u06cc-1.jpg 700w, https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/03\/\u067e\u0631\u062f\u0627\u0632\u0634-\u0645\u0648\u0627\u0632\u06cc-1-300x150.jpg 300w, https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/03\/\u067e\u0631\u062f\u0627\u0632\u0634-\u0645\u0648\u0627\u0632\u06cc-1-200x100.jpg 200w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D9%85%D9%88%D8%A7%D8%B2%DB%8C_%D8%AF%D8%B1_%D9%86%D8%AC%D9%88%D9%85\"><\/span><strong>\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u0646\u062c\u0648\u0645<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0646\u062c\u0648\u0645 \u0628\u0647 \u06a9\u0646\u062f\u06cc \u062d\u0631\u06a9\u062a \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0645\u06cc\u0644\u06cc\u0648\u0646\u200c\u0647\u0627 \u0633\u0627\u0644 \u0637\u0648\u0644 \u0645\u06cc\u200c\u06a9\u0634\u062f \u062a\u0627 \u0633\u062a\u0627\u0631\u0647\u200c\u0647\u0627 \u0628\u0627 \u0647\u0645 \u0628\u0631\u062e\u0648\u0631\u062f \u06a9\u0646\u0646\u062f\u060c \u06a9\u0647\u06a9\u0634\u0627\u0646\u200c\u0647\u0627 \u0627\u062f\u063a\u0627\u0645 \u0634\u0648\u0646\u062f \u06cc\u0627 \u0633\u06cc\u0627\u0647\u200c \u0686\u0627\u0644\u0647\u200c\u0647\u0627 \u0627\u062c\u0631\u0627\u0645 \u0646\u062c\u0648\u0645\u06cc \u0631\u0627 \u0628\u0628\u0644\u0639\u0646\u062f \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u0627\u0633\u062a \u06a9\u0647 \u0627\u062e\u062a\u0631\u0634\u0646\u0627\u0633\u0627\u0646 \u0648 \u0641\u06cc\u0632\u06cc\u06a9\u062f\u0627\u0646\u0627\u0646 \u0628\u0631\u0627\u06cc \u0645\u0637\u0627\u0644\u0639\u0647 \u0627\u06cc\u0646 \u0646\u0648\u0639 \u0641\u0631\u0622\u06cc\u0646\u062f\u0647\u0627 \u0628\u0627\u06cc\u062f \u0628\u0647 \u0634\u0628\u06cc\u0647\u200c \u0633\u0627\u0632\u06cc\u200c\u0647\u0627\u06cc \u06a9\u0627\u0645\u067e\u06cc\u0648\u062a\u0631\u06cc \u0631\u0648\u06cc \u0628\u06cc\u0627\u0648\u0631\u0646\u062f. \u0648 \u0686\u0646\u06cc\u0646 \u0645\u062f\u0644\u200c\u0647\u0627\u06cc \u067e\u06cc\u0686\u06cc\u062f\u0647\u200c\u0627\u06cc \u0628\u0647 \u062a\u0648\u0627\u0646 \u0645\u062d\u0627\u0633\u0628\u0627\u062a\u06cc \u0639\u0638\u06cc\u0645 \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u0646\u062f.<\/p>\n<p style=\"text-align: justify;\">\u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0645\u062b\u0627\u0644: \u067e\u06cc\u0634\u0631\u0641\u062a\u200c\u0647\u0627\u06cc \u0627\u062e\u06cc\u0631 \u062f\u0631 \u0645\u0648\u0631\u062f \u0645\u0637\u0627\u0644\u0639\u0647 \u06cc\u06a9 \u0633\u06cc\u0627\u0647 \u0686\u0627\u0644\u0647\u060c \u0628\u0647 \u0644\u0637\u0641 \u06cc\u06a9 \u0627\u0628\u0631 <a href=\"https:\/\/rahaco.net\/thinclient\/\">\u0631\u0627\u06cc\u0627\u0646\u0647<\/a> \u0645\u0648\u0627\u0632\u06cc \u0627\u062a\u0641\u0627\u0642 \u0627\u0641\u062a\u0627\u062f. \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0627\u0628\u0631 \u0631\u0627\u06cc\u0627\u0646\u0647 \u0645\u0648\u0627\u0632\u06cc \u0645\u062d\u0642\u0642\u0627\u0646 \u062a\u0648\u0627\u0646\u0633\u062a\u0646\u062f \u06cc\u06a9 \u0631\u0627\u0632 \u0686\u0647\u0627\u0631 \u062f\u0647\u0647\u200c\u0627\u06cc \u0631\u0627 \u062d\u0644 \u06a9\u0646\u0646\u062f \u0648 \u062b\u0627\u0628\u062a \u06a9\u0631\u062f\u0646\u062f \u06a9\u0647 \u062f\u0631\u0648\u0646\u06cc\u200c\u062a\u0631\u06cc\u0646 \u0642\u0633\u0645\u062a \u0645\u0627\u062f\u0647 \u0628\u0647 \u062f\u0648\u0631 \u0622\u0646 \u0645\u06cc\u200c\u0686\u0631\u062e\u062f \u0648 \u0633\u067e\u0633 \u0628\u0647 \u062f\u0631\u0648\u0646 \u0622\u0646 \u0641\u0631\u0648 \u0645\u06cc\u200c\u0631\u06cc\u0632\u062f. \u0627\u06cc\u0646 \u06a9\u0644\u06cc\u062f \u06a9\u0645\u06a9 \u06a9\u0646\u0646\u062f\u0647 \u0628\u0647 \u062f\u0627\u0646\u0634\u0645\u0646\u062f\u0627\u0646 \u0628\u0631\u0627\u06cc \u062f\u0631\u06a9 \u0628\u0647\u062a\u0631 \u0646\u062d\u0648\u0647 \u0631\u0641\u062a\u0627\u0631 \u0627\u06cc\u0646 \u067e\u062f\u06cc\u062f\u0647 \u0645\u0631\u0645\u0648\u0632 \u0627\u0633\u062a.<\/p>\n<p style=\"text-align: justify;\">\u0645\u062d\u0642\u0642 \u0627\u0644\u06a9\u0633\u0627\u0646\u062f\u0631 \u0686\u062e\u0648\u0641\u0633\u06a9\u06cc \u0627\u0632 \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0646\u0648\u0631\u062b \u0648\u0633\u062a\u0631\u0646 \u06a9\u0647 \u0628\u0627 \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0622\u0645\u0633\u062a\u0631\u062f\u0627\u0645 \u0648 \u062f\u0627\u0646\u0634\u06af\u0627\u0647 \u0622\u06a9\u0633\u0641\u0648\u0631\u062f \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0637\u0627\u0644\u0639\u0647 \u0647\u0645\u06a9\u0627\u0631\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u0645\u06cc\u200c\u06af\u0648\u06cc\u062f: \u0627\u06cc\u0646 \u062c\u0632\u0626\u06cc\u0627\u062a \u062f\u0631 \u0627\u0637\u0631\u0627\u0641 \u0633\u06cc\u0627\u0647 \u0686\u0627\u0644\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u06a9\u0648\u0686\u06a9 \u0628\u0647 \u0646\u0638\u0631 \u0628\u0631\u0633\u0646\u062f\u060c \u0627\u0645\u0627 \u0622\u0646\u200c\u0647\u0627 \u0628\u0647 \u0634\u062f\u062a \u0628\u0631 \u0622\u0646\u0686\u0647 \u062f\u0631 \u06a9\u0647\u06a9\u0634\u0627\u0646 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u06a9\u0644 \u0627\u062a\u0641\u0627\u0642 \u0645\u06cc\u200c\u0627\u0641\u062a\u062f \u062a\u0627\u062b\u06cc\u0631 \u0645\u06cc\u200c\u06af\u0630\u0627\u0631\u0646\u062f. \u0622\u0646\u200c\u0647\u0627 \u0633\u0631\u0639\u062a \u0686\u0631\u062e\u0634 \u0633\u06cc\u0627\u0647 \u0686\u0627\u0644\u0647\u200c\u0647\u0627 \u0631\u0627 \u06a9\u0646\u062a\u0631\u0644 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u0648 \u062f\u0631 \u0627\u062e\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0645\u062a\u0648\u062c\u0647 \u0634\u0648\u0646\u062f \u06a9\u0647 \u0633\u06cc\u0627\u0647 \u0686\u0627\u0644\u0647\u200c\u0647\u0627 \u0686\u0647 \u062a\u0627\u062b\u06cc\u0631\u06cc \u0628\u0631 \u06a9\u0644 \u06a9\u0647\u06a9\u0634\u0627\u0646\u200c\u0647\u0627 \u062f\u0627\u0631\u0646\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D9%85%D9%88%D8%A7%D8%B2%DB%8C_%D8%AF%D8%B1_%DA%A9%D8%B4%D8%A7%D9%88%D8%B1%D8%B2%DB%8C\"><\/span><strong>\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0647\u0631 \u0645\u0627\u0647\u060c \u0648\u0632\u0627\u0631\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0627\u06cc\u0627\u0644\u0627\u062a \u0645\u062a\u062d\u062f\u0647 \u0627\u0631\u0642\u0627\u0645 \u0639\u0631\u0636\u0647 \u0648 \u062a\u0642\u0627\u0636\u0627 \u0631\u0627 \u0628\u0631\u0627\u06cc \u062a\u0639\u062f\u0627\u062f\u06cc \u0627\u0632 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0639\u0645\u062f\u0647 \u0628\u0631\u0622\u0648\u0631\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u067e\u06cc\u0634\u200c \u0628\u06cc\u0646\u06cc\u200c\u0647\u0627\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0645\u0647\u0645 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0631 \u0632\u0646\u062f\u06af\u06cc \u0627\u0641\u0631\u0627\u062f \u062a\u0627\u062b\u06cc\u0631 \u0628\u06af\u0630\u0627\u0631\u062f\u060c \u0627\u0632 \u0642\u0627\u0646\u0648\u0646 \u200c\u06af\u0630\u0627\u0631\u0627\u0646\u06cc \u06a9\u0647 \u062f\u0631 \u062a\u0644\u0627\u0634 \u0628\u0631\u0627\u06cc \u062b\u0628\u0627\u062a \u0628\u0627\u0632\u0627\u0631 \u0647\u0633\u062a\u0646\u062f \u062a\u0627 \u06a9\u0634\u0627\u0648\u0631\u0632\u0627\u0646\u06cc \u06a9\u0647 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u0646\u062f \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc \u062e\u0648\u062f \u0631\u0627 \u0645\u062f\u06cc\u0631\u06cc\u062a \u06a9\u0646\u0646\u062f. \u0633\u0627\u0644 \u06af\u0630\u0634\u062a\u0647\u060c \u0645\u062d\u0642\u0642\u0627\u0646 \u062f\u067e\u0627\u0631\u062a\u0645\u0627\u0646 \u0645\u0646\u0627\u0628\u0639 \u0637\u0628\u06cc\u0639\u06cc \u0648 \u0639\u0644\u0648\u0645 \u0645\u062d\u06cc\u0637\u06cc U of I \u0628\u0627 \u062a\u0631\u06a9\u06cc\u0628 \u062f\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u0631\u0634\u062f \u0645\u062d\u0635\u0648\u0644 \u0648 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0622\u0628 \u0648 \u0647\u0648\u0627\u06cc \u0641\u0635\u0644\u06cc \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u0631\u0642\u0627\u0645 \u0645\u0627\u0647\u0648\u0627\u0631\u0647\u200c\u0627\u06cc \u067e\u06cc\u0634\u200c \u0628\u06cc\u0646\u06cc \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0635\u0646\u0639\u062a \u0641\u062f\u0631\u0627\u0644 \u0631\u0632\u0631\u0648 \u0631\u0627 \u062f\u0631 \u0635\u062f\u0631 \u0642\u0631\u0627\u0631 \u062f\u0627\u062f\u0646\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D9%85%D9%88%D8%A7%D8%B2%DB%8C_%D8%AF%D8%B1_%D8%A7%D9%82%D8%AA%D8%B5%D8%A7%D8%AF_%D8%AC%D8%A7%D9%85%D8%B9%D9%87\"><\/span><strong>\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u0627\u0642\u062a\u0635\u0627\u062f \u062c\u0627\u0645\u0639\u0647<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0645\u0633\u0627\u0626\u0644 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u062c\u0627\u0645\u0639\u0647: \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u0628\u0631\u0627\u06cc \u0645\u062f\u0644 \u200c\u0633\u0627\u0632\u06cc \u0627\u0642\u062a\u0635\u0627\u062f \u06cc\u06a9 \u062c\u0647\u0627\u0646 \u06cc\u0627 \u0645\u0644\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0633\u06cc\u0633\u062a\u0645 \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0647\u0627 \u06a9\u0647 \u0634\u0627\u0645\u0644 \u062f\u0633\u062a\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0645\u062d\u0627\u0633\u0628\u0647 \u062e\u0648\u0634\u0647\u200c\u0627\u06cc \u0647\u0633\u062a\u0646\u062f\u060c \u0628\u0631\u0627\u06cc \u067e\u06cc\u0627\u062f\u0647\u200c \u0633\u0627\u0632\u06cc \u0627\u0644\u06af\u0648\u0631\u06cc\u062a\u0645\u200c\u0647\u0627\u06cc \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u0631\u0627\u0633\u062a\u0627\u06cc \u0628\u0647\u06cc\u0646\u0647\u200c \u0633\u0627\u0632\u06cc \u062f\u0631 \u0627\u0646\u0648\u0627\u0639 \u0645\u062f\u0644\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D9%85%D9%88%D8%A7%D8%B2%DB%8C_%D8%AF%D8%B1_%D8%AA%D8%AC%D8%A7%D8%B1%D8%AA\"><\/span><strong>\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u062a\u062c\u0627\u0631\u062a <\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0645\u062d\u0627\u0633\u0628\u0627\u062a \u0645\u0648\u0627\u0632\u06cc \u0627\u063a\u0644\u0628 \u062f\u0631 \u062d\u0648\u0632\u0647 \u0645\u0648\u0633\u0633\u0627\u062a \u062a\u062d\u0642\u06cc\u0642\u0627\u062a\u06cc \u062f\u0627\u0646\u0634\u06af\u0627\u0647\u06cc \u0648 \u062f\u0648\u0644\u062a\u06cc \u0627\u0633\u062a. \u062f\u0631 \u0635\u0646\u0639\u062a \u0628\u0627\u0646\u06a9\u062f\u0627\u0631\u06cc\u060c \u0645\u0639\u0627\u0645\u0644\u0647 \u200c\u06af\u0631\u0627\u0646 \u0648 \u0635\u0646\u0639\u062a \u0633\u0631\u0645\u0627\u06cc\u0647\u200c \u06af\u0630\u0627\u0631\u06cc\u060c \u0627\u0631\u0632\u0647\u0627\u06cc \u0631\u0645\u0632\u0646\u06af\u0627\u0631\u06cc \u0634\u062f\u0647 \u0627\u06cc\u0646\u200c\u0647\u0627 \u0647\u0645\u0647 \u062c\u0648\u0627\u0645\u0639 \u0628\u0632\u0631\u06af\u06cc \u0647\u0633\u062a\u0646\u062f. \u06a9\u0647 \u0627\u0632 \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647\u200c\u0647\u0627\u06cc \u06af\u0631\u0627\u0641\u06cc\u06a9\u06cc \u0632\u06cc\u0627\u062f\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0633\u0628 \u062f\u0631\u0622\u0645\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u0645\u0648\u0627\u0632\u06cc \u0646\u06cc\u0632 \u0631\u06cc\u0634\u0647 \u062f\u0631 \u062f\u0646\u06cc\u0627\u06cc \u0633\u0631\u06af\u0631\u0645\u06cc \u062f\u0627\u0631\u062f. \u0632\u06cc\u0631\u0627 GPU\u0647\u0627 \u062f\u0631 \u0627\u0628\u062a\u062f\u0627 \u0628\u0631\u0627\u06cc \u0628\u0627\u0631\u0647\u0627\u06cc \u06af\u0631\u0627\u0641\u06cc\u06a9\u06cc \u0633\u0646\u06af\u06cc\u0646 \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0628\u0631\u0627\u06cc \u0635\u0646\u0627\u06cc\u0639\u06cc \u06a9\u0647 \u0628\u0647 \u062f\u06cc\u0646\u0627\u0645\u06cc\u06a9 \u0633\u06cc\u0627\u0644\u0627\u062a \u0645\u062d\u0627\u0633\u0628\u0627\u062a\u06cc \u0645\u062a\u06a9\u06cc \u0647\u0633\u062a\u0646\u062f\u060c \u06cc\u06a9 \u062a\u062d\u0644\u06cc\u0644 \u0645\u06a9\u0627\u0646\u06cc\u06a9\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0686\u0646\u062f\u06cc\u0646 \u06a9\u0627\u0631\u0628\u0631\u062f \u062a\u062c\u0627\u0631\u06cc \u0628\u0632\u0631\u06af \u062f\u0627\u0631\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%86%D8%AD%D9%88%D9%87_%D8%A7%D8%B3%D8%AA%D9%81%D8%A7%D8%AF%D9%87_%D8%A7%D8%B2_%D9%85%D8%AD%D8%A7%D8%B3%D8%A8%D8%A7%D8%AA_%D9%85%D9%88%D8%A7%D8%B2%DB%8C_%D8%AF%D8%B1_%D8%AA%D8%AC%D8%A7%D8%B1%D8%AA\"><\/span><strong>\u0646\u062d\u0648\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u062a\u062c\u0627\u0631\u062a<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u062a\u0642\u0631\u06cc\u0628\u0627 \u062a\u0645\u0627\u0645 \u062c\u0646\u0628\u0647\u200c\u0647\u0627\u06cc \u0627\u0635\u0644\u06cc \u0628\u0627\u0646\u06a9\u062f\u0627\u0631\u06cc \u0627\u0645\u0631\u0648\u0632\u06cc\u060c \u0627\u0632 \u0627\u0645\u062a\u06cc\u0627\u0632\u062f\u0647\u06cc \u0627\u0639\u062a\u0628\u0627\u0631 \u06af\u0631\u0641\u062a\u0647 \u062a\u0627 \u0645\u062f\u0644 \u0633\u0627\u0632\u06cc \u0631\u06cc\u0633\u06a9 \u0648 \u06a9\u0634\u0641 \u062a\u0642\u0644\u0628\u060c \u0628\u0627 \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647\u200c\u0647\u0627\u06cc \u06af\u0631\u0627\u0641\u06cc\u06a9\u06cc \u062a\u0633\u0631\u06cc\u0639 \u06cc\u0627\u0641\u062a\u0647 \u0627\u0633\u062a. \u0628\u0647 \u0646\u0648\u0639\u06cc\u060c \u0627\u0646\u062d\u0631\u0627\u0641 \u0627\u0632 \u062a\u062c\u0632\u06cc\u0647 \u0648 \u062a\u062d\u0644\u06cc\u0644 \u0633\u0646\u062a\u06cc \u0645\u0628\u062a\u0646\u06cc \u0628\u0631 CPU \u0627\u062c\u062a\u0646\u0627\u0628 \u0646\u0627\u067e\u0630\u06cc\u0631 \u0628\u0648\u062f. \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0648\u0644\u06cc\u0646 \u067e\u0630\u06cc\u0631\u0646\u062f\u06af\u0627\u0646 JPMorgan Chase \u0628\u0648\u062f. \u06a9\u0647 \u062f\u0631 \u0633\u0627\u0644 2011 \u0627\u0639\u0644\u0627\u0645 \u06a9\u0631\u062f \u06a9\u0647 \u062a\u063a\u06cc\u06cc\u0631 \u0627\u0632 \u067e\u0631\u062f\u0627\u0632\u0634 \u062a\u0631\u06a9\u06cc\u0628\u06cc CPU \u0628\u0647 GPU-CPU \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u062f\u0631 \u0645\u0631\u0627\u06a9\u0632 \u062f\u0627\u062f\u0647 \u062e\u0648\u062f \u0631\u0627 \u062a\u0627 40 \u062f\u0631\u0635\u062f \u0628\u0647\u0628\u0648\u062f \u062f\u0627\u062f\u0647 \u0648 80 \u062f\u0631\u0635\u062f \u0635\u0631\u0641\u0647 \u062c\u0648\u06cc\u06cc \u0631\u0627 \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u062f\u0627\u0634\u062a\u0647 \u0627\u0633\u062a. \u0627\u062e\u06cc\u0631\u0627 \u0648\u0644\u0632 \u0641\u0627\u0631\u06af\u0648 \u0627\u0632 \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647\u200c\u0647\u0627\u06cc \u06af\u0631\u0627\u0641\u06cc\u06a9\u06cc \u0627\u0646\u0648\u06cc\u062f\u06cc\u0627 \u0628\u0631\u0627\u06cc \u0641\u0631\u0622\u06cc\u0646\u062f\u0647\u0627\u06cc\u06cc \u0645\u0627\u0646\u0646\u062f: \u062a\u0633\u0631\u06cc\u0639 \u0645\u062f\u0644\u200c\u0647\u0627\u06cc \u0647\u0648\u0634 \u0645\u0635\u0646\u0648\u0639\u06cc \u0628\u0631\u0627\u06cc \u0631\u06cc\u0633\u06a9 \u0646\u0642\u062f\u06cc\u0646\u06af\u06cc \u0648 <a href=\"https:\/\/rahaco.net\/virtualization\/\">\u0645\u062c\u0627\u0632\u06cc \u200c\u0633\u0627\u0632\u06cc<\/a> \u062f\u0633\u06a9\u062a\u0627\u067e \u062e\u0648\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%86%D8%AD%D9%88%D9%87_%D8%A7%D8%B3%D8%AA%D9%81%D8%A7%D8%AF%D9%87_%D8%A7%D8%B2_%D9%85%D8%AD%D8%A7%D8%B3%D8%A8%D8%A7%D8%AA_%D9%85%D9%88%D8%A7%D8%B2%DB%8C_%D8%AF%D8%B1_%D9%85%D8%B5%D8%B1%D9%81_%D8%A7%D9%86%D8%B1%DA%98%DB%8C\"><\/span><strong>\u0646\u062d\u0648\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u0645\u0635\u0631\u0641 \u0627\u0646\u0631\u0698\u06cc<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0632\u0631\u06af\u200c\u062a\u0631\u06cc\u0646 \u0627\u0641\u0631\u0627\u062f \u062f\u0631 \u0635\u0646\u0639\u062a \u0646\u0641\u062a \u062f\u0631 \u062d\u0648\u0645\u0647 \u0647\u06cc\u0648\u0633\u062a\u0648\u0646 \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 Bubba \u0646\u0627\u0645 \u062f\u0627\u0631\u062f. Bubba \u06cc\u06a9 \u0627\u0628\u0631 \u0631\u0627\u06cc\u0627\u0646\u0647 (\u062f\u0631 \u0645\u06cc\u0627\u0646 \u0633\u0631\u06cc\u0639\u200c\u062a\u0631\u06cc\u0646\u200c\u0647\u0627\u06cc \u0627\u0628\u0631 \u0631\u0627\u06cc\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0631\u0648\u06cc \u06a9\u0631\u0647 \u0632\u0645\u06cc\u0646) \u0627\u0633\u062a \u06a9\u0647 \u0645\u062a\u0639\u0644\u0642 \u0628\u0647 \u0634\u0631\u06a9\u062a \u0698\u0626\u0648\u067e\u0631\u062f\u0627\u0632\u0634 \u0627\u0633\u062a\u0631\u0627\u0644\u06cc\u0627\u06cc\u06cc Down Under Geo Solutions \u0645\u06cc\u200c\u0628\u0627\u0634\u062f. \u067e\u0631\u062f\u0627\u0632\u0634 \u062f\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u0644\u0631\u0632\u0647\u200c\u0627\u06cc \u0645\u062f\u062a\u200c\u0647\u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u0627\u0631\u0627\u0626\u0647 \u062a\u0635\u0648\u06cc\u0631 \u0648\u0627\u0636\u062d\u200c\u062a\u0631\u06cc \u0627\u0632 \u0644\u0627\u06cc\u0647\u200c\u0647\u0627\u06cc \u0632\u06cc\u0631 \u0632\u0645\u06cc\u0646\u06cc \u06a9\u0645\u06a9 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a\u060c \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0635\u0646\u0627\u06cc\u0639\u06cc \u0645\u0627\u0646\u0646\u062f: \u0646\u0641\u062a \u0648 \u06af\u0627\u0632 \u0636\u0631\u0648\u0631\u06cc \u0627\u0633\u062a. \u0628\u0627 \u0627\u06cc\u0646 \u062d\u0627\u0644\u060c \u0627\u0628\u0631 \u0631\u0627\u06cc\u0627\u0646\u0647 \u0627\u0645\u0631\u0648\u0632\u0647 \u062f\u0631 \u062d\u0641\u0627\u0631\u06cc \u0627\u0646\u0631\u0698\u06cc \u0639\u0645\u0644\u0627 \u0627\u0645\u0631\u06cc \u063a\u06cc\u0631 \u0645\u0639\u0645\u0648\u0644 \u0627\u0633\u062a. \u0628\u0647 \u0648\u06cc\u0698\u0647 \u0647\u0646\u06af\u0627\u0645\u06cc \u06a9\u0647 \u0627\u0644\u06af\u0648\u0631\u06cc\u062a\u0645\u200c\u0647\u0627 \u0645\u0642\u0627\u062f\u06cc\u0631 \u0639\u0638\u06cc\u0645\u06cc \u0627\u0632 \u062f\u0627\u062f\u0647 \u0631\u0627 \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u062a\u0627 \u0628\u0647 \u062d\u0641\u0627\u0631\u06cc\u200c\u0647\u0627 \u062f\u0631 \u0627\u0633\u062a\u062e\u0631\u0627\u062c \u0632\u0645\u06cc\u0646\u200c\u0647\u0627\u06cc \u062f\u0634\u0648\u0627\u0631 \u0645\u0627\u0646\u0646\u062f \u06af\u0646\u0628\u062f\u0647\u0627\u06cc \u0646\u0645\u06a9\u06cc \u06a9\u0645\u06a9 \u06a9\u0646\u0646\u062f.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-12157\" src=\"https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/03\/\u06a9\u0627\u0631\u0628\u0631\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0645\u0648\u0627\u0632\u06cc.jpg\" alt=\"\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc\" width=\"845\" height=\"576\" srcset=\"https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/03\/\u06a9\u0627\u0631\u0628\u0631\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0645\u0648\u0627\u0632\u06cc.jpg 1000w, https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/03\/\u06a9\u0627\u0631\u0628\u0631\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0645\u0648\u0627\u0632\u06cc-300x205.jpg 300w, https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/03\/\u06a9\u0627\u0631\u0628\u0631\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0645\u0648\u0627\u0632\u06cc-768x524.jpg 768w\" sizes=\"(max-width: 845px) 100vw, 845px\" \/><\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D9%85%D9%88%D8%A7%D8%B2%DB%8C_%D8%AF%D8%B1_%D9%BE%D8%B2%D8%B4%DA%A9%DB%8C_%D9%88_%DA%A9%D8%B4%D9%81_%D8%AF%D8%A7%D8%B1%D9%88\"><\/span><strong>\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u067e\u0632\u0634\u06a9\u06cc \u0648 \u06a9\u0634\u0641 \u062f\u0627\u0631\u0648<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0641\u0646\u0627\u0648\u0631\u06cc\u200c\u0647\u0627\u06cc \u0646\u0648\u0638\u0647\u0648\u0631 \u0628\u0647 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0628\u06cc\u200c\u0634\u0645\u0627\u0631\u06cc \u0686\u0634\u0645 \u200c\u0627\u0646\u062f\u0627\u0632 \u067e\u0632\u0634\u06a9\u06cc \u0631\u0627 \u062a\u063a\u06cc\u06cc\u0631 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f\u060c \u0627\u0632 \u0648\u0627\u0642\u0639\u06cc\u062a \u0645\u062c\u0627\u0632\u06cc \u06a9\u0647 \u062f\u0698\u0646\u0631\u0627\u0633\u06cc\u0648\u0646 \u0645\u0627\u06a9\u0648\u0644\u0627 (\u0644\u06a9\u0647\u200c\u0627\u06cc \u0632\u0631\u062f \u062f\u0631 \u0686\u0634\u0645\u060c \u0646\u0648\u0639\u06cc \u0628\u06cc\u0645\u0627\u0631\u06cc \u0686\u0634\u0645\u06cc \u0627\u0633\u062a) \u0631\u0627 \u0628\u0647\u0628\u0648\u062f \u0645\u06cc\u200c\u0628\u062e\u0634\u062f \u062a\u0627 \u067e\u06cc\u0634\u0631\u0641\u062a\u200c\u0647\u0627 \u062f\u0631 \u0686\u0627\u067e \u0632\u06cc\u0633\u062a\u06cc \u0628\u0627\u0641\u062a \u0627\u0633\u062a. \u0686\u0627\u067e \u0632\u06cc\u0633\u062a\u06cc \u0634\u0627\u0645\u0644 \u0641\u0646\u0627\u0648\u0631\u06cc \u0686\u0627\u067e \u0633\u0647 \u0628\u0639\u062f\u06cc \u0628\u0631\u0627\u06cc \u0633\u0627\u062e\u062a\u0646 \u0628\u0627\u0641\u062a\u200c\u0647\u0627 \u0648 \u0627\u0646\u062f\u0627\u0645\u200c\u0647\u0627 \u0645\u06cc\u200c\u0628\u0627\u0634\u062f. \u0627\u0646\u062f\u0627\u0645\u200c\u0647\u0627\u060c \u0631\u0627\u0647\u200c\u0647\u0627\u06cc \u0628\u06cc\u200c\u0634\u0645\u0627\u0631\u06cc \u0628\u0631\u0627\u06cc \u062a\u0627\u062b\u06cc\u0631 \u0628\u06cc\u0634\u062a\u0631 \u0628\u0631 \u0645\u0631\u0627\u0642\u0628\u062a\u200c\u0647\u0627\u06cc \u0628\u0647\u062f\u0627\u0634\u062a\u06cc \u062f\u0627\u0631\u062f. \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u0645\u0648\u0627\u0632\u06cc\u00a0 \u0628\u0647 \u067e\u06cc\u0634\u0631\u0641\u062a\u200c\u0647\u0627\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc \u06a9\u0645\u06a9 \u06a9\u0646\u062f.<\/p>\n<p style=\"text-align: justify;\">\u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc \u062a\u062d\u0642\u06cc\u0642\u0627\u062a\u06cc \u067e\u0632\u0634\u06a9\u06cc \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0647\u0627\u06cc \u0645\u062a\u0639\u062f\u062f\u06cc \u0631\u0627 \u062a\u0648\u0633\u0639\u0647 \u062f\u0627\u062f\u0647\u200c\u0627\u0646\u062f \u06a9\u0647 \u0627\u0632 \u0632\u06cc\u0631 \u0633\u0627\u062e\u062a \u0628\u0627\u0631\u06af\u0630\u0627\u0631\u06cc \u0642\u062f\u0631\u062a\u0645\u0646\u062f GPU\u0647\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0628\u0627 \u0627\u0646\u062c\u0627\u0645 \u0634\u0628\u06cc\u0647 \u200c\u0633\u0627\u0632\u06cc \u0631\u0648\u06cc \u0628\u0631\u062e\u06cc \u0627\u0632 \u0642\u0648\u06cc\u200c\u062a\u0631\u06cc\u0646 \u0631\u0627\u06cc\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u062c\u0647\u0627\u0646\u060c \u062f\u0627\u0646\u0634\u0645\u0646\u062f\u0627\u0646 \u062a\u0648\u0627\u0646\u0633\u062a\u0646\u062f \u062a\u0627 \u0646\u062d\u0648\u0647 \u0627\u0631\u062a\u0628\u0627\u0637 \u0627\u0646\u062a\u0642\u0627\u0644\u200c \u062f\u0647\u0646\u062f\u0647\u200c\u0647\u0627\u06cc \u0639\u0635\u0628\u06cc \u0631\u0627 \u0628\u0647\u062a\u0631 \u062f\u0631\u06a9 \u06a9\u0646\u0646\u062f. \u0627\u0632 \u0622\u0646\u062c\u0627\u06cc\u06cc \u06a9\u0647 \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u0645\u0648\u0627\u0632\u06cc \u067e\u06cc\u0634\u0631\u0641\u062a\u0647 \u0627\u0645\u06a9\u0627\u0646 \u0645\u0637\u0627\u0644\u0639\u0647 \u062f\u0642\u06cc\u0642 \u0645\u0627\u0634\u06cc\u0646\u200c\u0647\u0627\u06cc \u0645\u0648\u0644\u06a9\u0648\u0644\u06cc \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u06a9\u0627\u0631\u0628\u0631\u062f\u0647\u0627\u06cc \u0639\u0645\u062f\u0647\u200c\u0627\u06cc \u062f\u0631 \u0645\u0637\u0627\u0644\u0639\u0647 \u0628\u06cc\u0645\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc \u0698\u0646\u062a\u06cc\u06a9\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f \u0686\u06cc\u0632\u06cc \u06a9\u0647 \u0645\u062d\u0642\u0642\u0627\u0646 \u062f\u0631 \u062d\u0627\u0644 \u062d\u0627\u0636\u0631 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0622\u0646 \u0647\u0633\u062a\u0646\u062f.<\/p>\n<p style=\"text-align: justify;\">\u0646\u0631\u0645\u200c\u0627\u0641\u0632\u0627\u0631 \u067e\u0632\u0634\u06a9\u06cc: \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u067e\u0631\u062f\u0627\u0632\u0634 \u062a\u0635\u0648\u06cc\u0631 \u067e\u0632\u0634\u06a9\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0645\u062b\u0627\u0644 \u0628\u0631\u0627\u06cc \u0627\u0633\u06a9\u0646 \u0628\u062f\u0646 \u0627\u0646\u0633\u0627\u0646 \u0648 \u0627\u0633\u06a9\u0646 \u0645\u063a\u0632 \u0627\u0646\u0633\u0627\u0646\u060c \u062f\u0631 \u0628\u0627\u0632\u0633\u0627\u0632\u06cc MRI \u0628\u0631\u0627\u06cc \u062a\u0634\u062e\u06cc\u0635 \u0645\u0647\u0631\u0647\u200c\u0647\u0627 \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f.\u0686\u06af\u0648\u0646\u0647 \u0627\u0632 \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u0645\u0648\u0627\u0632\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f: \u0641\u0631\u0627\u062a\u0631 \u0627\u0632 \u0631\u0646\u062f\u0631 \u062a\u0635\u0648\u06cc\u0631 \u0648 \u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u062f\u0627\u0631\u0648\u06cc\u06cc\u060c \u0642\u062f\u0631\u062a \u062a\u062c\u0632\u06cc\u0647 \u0648 \u062a\u062d\u0644\u06cc\u0644 \u062f\u0627\u062f\u0647\u200c\u0647\u0627 \u062f\u0631 \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u0646\u0648\u06cc\u062f \u0628\u062e\u0634 \u0633\u0644\u0627\u0645\u062a \u0639\u0645\u0648\u0645\u06cc \u0627\u0633\u062a.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%86%D8%AA%DB%8C%D8%AC%D9%87_%DA%AF%DB%8C%D8%B1%DB%8C\"><\/span><strong>\u0646\u062a\u06cc\u062c\u0647 \u06af\u06cc\u0631\u06cc<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0628\u0627 \u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u0635\u0646\u0639\u062a\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0648 \u0645\u0647\u0645\u06cc \u0622\u0634\u0646\u0627 \u0634\u062f\u06cc\u0645 \u0648 \u0646\u0642\u0634 \u0622\u0646 \u0631\u0627 \u062f\u0631 \u0627\u0646\u062c\u0627\u0645 \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u062f\u0631\u06a9 \u06a9\u0631\u062f\u06cc\u0645. \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u0631\u0648\u0634\u06cc \u0628\u0631\u0627\u06cc \u0645\u062d\u0627\u0633\u0628\u0647 \u0627\u062c\u0631\u0627\u06cc \u062f\u0648 \u06cc\u0627 \u0686\u0646\u062f \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647 (CPU) \u0628\u0631\u0627\u06cc \u0631\u0633\u06cc\u062f\u06af\u06cc \u0628\u0647 \u0628\u062e\u0634\u200c\u0647\u0627\u06cc \u062c\u062f\u0627\u06af\u0627\u0646\u0647 \u06cc\u06a9 \u06a9\u0627\u0631 \u06a9\u0644\u06cc \u0627\u0633\u062a. \u062c\u062f\u0627 \u06a9\u0631\u062f\u0646 \u0628\u062e\u0634\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u06cc\u06a9 \u06a9\u0627\u0631 \u062f\u0631 \u0645\u06cc\u0627\u0646 \u0686\u0646\u062f\u06cc\u0646 \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647 \u0628\u0647 \u06a9\u0627\u0647\u0634 \u0632\u0645\u0627\u0646 \u0627\u062c\u0631\u0627\u06cc \u06cc\u06a9 \u0628\u0631\u0646\u0627\u0645\u0647 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0647\u0631 \u0633\u06cc\u0633\u062a\u0645\u06cc \u06a9\u0647 \u0628\u06cc\u0634 \u0627\u0632 \u06cc\u06a9 CPU \u062f\u0627\u0631\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647\u200c\u0647\u0627\u06cc \u0686\u0646\u062f \u0647\u0633\u062a\u0647\u200c\u0627\u06cc \u06a9\u0647 \u0627\u0645\u0631\u0648\u0632\u0647 \u0645\u0639\u0645\u0648\u0644\u0627 \u062f\u0631 \u0631\u0627\u06cc\u0627\u0646\u0647\u200c\u0647\u0627 \u06cc\u0627\u0641\u062a \u0645\u06cc\u200c\u0634\u0648\u0646\u062f\u060c \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u062f. \u062f\u0627\u0646\u0634\u0645\u0646\u062f\u0627\u0646 \u0627\u0632 \u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u0628\u0631\u0627\u06cc \u0627\u0646\u062c\u0627\u0645 \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<\/p>\n<h3 style=\"text-align: center;\"><span class=\"ez-toc-section\" id=\"%D8%AF%D8%A7%D9%86%D9%84%D9%88%D8%AF_PDF_%D9%85%D9%82%D8%A7%D9%84%D9%87_%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D9%85%D9%88%D8%A7%D8%B2%DB%8C\"><\/span><a href=\"https:\/\/rahaco.net\/mag\/pdf\/parallel-processing.pdf\"><span style=\"color: #ff6600;\">\u062f\u0627\u0646\u0644\u0648\u062f PDF \u0645\u0642\u0627\u0644\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc<\/span><\/a><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;12015&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;5&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;0&quot;,&quot;greet&quot;:&quot;\u062b\u0628\u062a \u0627\u0645\u062a\u06cc\u0627\u0632 post&quot;,&quot;legend&quot;:&quot;5\\\/5 - (5 \u0627\u0645\u062a\u06cc\u0627\u0632)&quot;,&quot;size&quot;:&quot;22&quot;,&quot;title&quot;:&quot;\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc\u061b \u0628\u0647\u062a\u0631\u06cc\u0646 \u0631\u0648\u0634 \u0628\u0631\u0627\u06cc \u0627\u0646\u062c\u0627\u0645 \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u067e\u06cc\u0686\u06cc\u062f\u0647&quot;,&quot;width&quot;:&quot;110&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-left: 0px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-left: 0px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-left: 0px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-left: 0px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-left: 0px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 110px;\">\n            <div class=\"kksr-star\" style=\"padding-left: 0px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 0px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 0px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 0px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 0px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 17.6px;\">\n            5\/5 - (5 \u0627\u0645\u062a\u06cc\u0627\u0632)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u0628\u0647 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0633\u0631\u0639\u062a \u0645\u062d\u0627\u0633\u0628\u0627\u062a\u06cc \u0648 \u062a\u0642\u0633\u06cc\u0645 \u0622\u0646 \u0628\u0647 \u06a9\u0627\u0631\u0647\u0627\u06cc \u06a9\u0648\u0686\u06a9\u200c\u062a\u0631 \u062f\u0631 \u0686\u0646\u062f\u06cc\u0646 \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647 \u0627\u0634\u0627\u0631\u0647 \u062f\u0627\u0631\u062f. \u0627\u06af\u0631 \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u0645\u0648\u0627\u0632\u06cc \u06cc\u06a9 \u062a\u0639\u0631\u06cc\u0641 \u06a9\u0644\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f\u060c \u0647\u0645\u06cc\u0646 &#8220;\u062a\u0642\u0633\u06cc\u0645&#8230;<\/p>\n","protected":false},"author":9,"featured_media":12020,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[100],"tags":[1400,1401],"class_list":["post-12015","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-1400","tag-1401"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0628\u0647\u06cc\u0646\u0647 \u0627\u0632 \u0645\u0646\u0627\u0628\u0639 | \u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u06cc \u0631\u0647\u0627 | \u0631\u0647\u0627\u0645\u06af<\/title>\n<meta name=\"description\" content=\"\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u0627\u0632 \u0646\u0638\u0631 \u0645\u062d\u0627\u0633\u0628\u0627\u062a\u06cc \u0628\u0627\u0639\u062b \u0627\u06cc\u062c\u0627\u062f \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u0639\u0645\u06cc\u0642 \u062f\u0631 \u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u062f\u0627\u0631\u0648\u06cc\u06cc\u060c \u0627\u06a9\u062a\u0634\u0627\u0641 \u0627\u0646\u0631\u0698\u06cc\u060c \u062a\u0635\u0648\u06cc\u0631\u0628\u0631\u062f\u0627\u0631\u06cc \u067e\u0632\u0634\u06a9\u06cc \u0648 \u0645\u0648\u0627\u0631\u062f \u062f\u06cc\u06af\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rahaco.net\/mag\/parallel-processing-application\/\" \/>\n<meta property=\"og:locale\" content=\"fa_IR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0628\u0647\u06cc\u0646\u0647 \u0627\u0632 \u0645\u0646\u0627\u0628\u0639 | \u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u06cc \u0631\u0647\u0627 | \u0631\u0647\u0627\u0645\u06af\" \/>\n<meta property=\"og:description\" content=\"\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u0627\u0632 \u0646\u0638\u0631 \u0645\u062d\u0627\u0633\u0628\u0627\u062a\u06cc \u0628\u0627\u0639\u062b \u0627\u06cc\u062c\u0627\u062f \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u0639\u0645\u06cc\u0642 \u062f\u0631 \u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u062f\u0627\u0631\u0648\u06cc\u06cc\u060c \u0627\u06a9\u062a\u0634\u0627\u0641 \u0627\u0646\u0631\u0698\u06cc\u060c \u062a\u0635\u0648\u06cc\u0631\u0628\u0631\u062f\u0627\u0631\u06cc \u067e\u0632\u0634\u06a9\u06cc \u0648 \u0645\u0648\u0627\u0631\u062f \u062f\u06cc\u06af\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rahaco.net\/mag\/parallel-processing-application\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u06cc \u0631\u0647\u0627 | \u0631\u0647\u0627\u0645\u06af\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rahacompanies\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-11T08:30:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-17T11:08:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/02\/\u06a9\u0627\u0631\u0628\u0631\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0645\u0648\u0627\u0632\u06cc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"686\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0645\u0647\u0633\u0627 \u0645\u062d\u0645\u062f\u0632\u0627\u062f\u0647\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CompaniesRaha\" \/>\n<meta name=\"twitter:site\" content=\"@CompaniesRaha\" \/>\n<meta name=\"twitter:label1\" content=\"\u0646\u0648\u0634\u062a\u0647 \u0634\u062f\u0647 \u062a\u0648\u0633\u0637\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0645\u0647\u0633\u0627 \u0645\u062d\u0645\u062f\u0632\u0627\u062f\u0647\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0632\u0645\u0627\u0646 \u062a\u062e\u0645\u06cc\u0646\u06cc \u0645\u0637\u0627\u0644\u0639\u0647\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 \u062f\u0642\u06cc\u0642\u0647\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/parallel-processing-application\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/parallel-processing-application\\\/\"},\"author\":{\"name\":\"\u0645\u0647\u0633\u0627 \u0645\u062d\u0645\u062f\u0632\u0627\u062f\u0647\",\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/#\\\/schema\\\/person\\\/fdf43ee5e6f75b62847abc89aeed6b93\"},\"headline\":\"\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc\u061b \u0628\u0647\u062a\u0631\u06cc\u0646 \u0631\u0648\u0634 \u0628\u0631\u0627\u06cc \u0627\u0646\u062c\u0627\u0645 \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u067e\u06cc\u0686\u06cc\u062f\u0647\",\"datePublished\":\"2023-03-11T08:30:24+00:00\",\"dateModified\":\"2023-07-17T11:08:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/parallel-processing-application\\\/\"},\"wordCount\":24,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/parallel-processing-application\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/\u06a9\u0627\u0631\u0628\u0631\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0645\u0648\u0627\u0632\u06cc.jpg\",\"keywords\":[\"\u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc\",\"\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc\"],\"articleSection\":[\"\u0627\u062e\u0628\u0627\u0631\"],\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rahaco.net\\\/mag\\\/parallel-processing-application\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/parallel-processing-application\\\/\",\"url\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/parallel-processing-application\\\/\",\"name\":\"\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0628\u0647\u06cc\u0646\u0647 \u0627\u0632 \u0645\u0646\u0627\u0628\u0639 | \u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u06cc \u0631\u0647\u0627 | \u0631\u0647\u0627\u0645\u06af\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/parallel-processing-application\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/parallel-processing-application\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/\u06a9\u0627\u0631\u0628\u0631\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0645\u0648\u0627\u0632\u06cc.jpg\",\"datePublished\":\"2023-03-11T08:30:24+00:00\",\"dateModified\":\"2023-07-17T11:08:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/#\\\/schema\\\/person\\\/fdf43ee5e6f75b62847abc89aeed6b93\"},\"description\":\"\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u0627\u0632 \u0646\u0638\u0631 \u0645\u062d\u0627\u0633\u0628\u0627\u062a\u06cc \u0628\u0627\u0639\u062b \u0627\u06cc\u062c\u0627\u062f \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u0639\u0645\u06cc\u0642 \u062f\u0631 \u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u062f\u0627\u0631\u0648\u06cc\u06cc\u060c \u0627\u06a9\u062a\u0634\u0627\u0641 \u0627\u0646\u0631\u0698\u06cc\u060c \u062a\u0635\u0648\u06cc\u0631\u0628\u0631\u062f\u0627\u0631\u06cc \u067e\u0632\u0634\u06a9\u06cc \u0648 \u0645\u0648\u0627\u0631\u062f \u062f\u06cc\u06af\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f.\",\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rahaco.net\\\/mag\\\/parallel-processing-application\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/parallel-processing-application\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/\u06a9\u0627\u0631\u0628\u0631\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0645\u0648\u0627\u0632\u06cc.jpg\",\"contentUrl\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/\u06a9\u0627\u0631\u0628\u0631\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0645\u0648\u0627\u0632\u06cc.jpg\",\"width\":1080,\"height\":686,\"caption\":\"\u06a9\u0627\u0631\u0628\u0631\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0645\u0648\u0627\u0632\u06cc\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/#website\",\"url\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/\",\"name\":\"\u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u06cc \u0631\u0647\u0627 | \u0631\u0647\u0627\u0645\u06af\",\"description\":\"\u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u064a \u0647\u0627\u064a \u064a\u06a9 \u0634\u0647\u0631 \u0647\u0648\u0634\u0645\u0646\u062f \u0631\u0627 \u0628\u0627 \u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u064a \u0631\u0647\u0627 \u062a\u062c\u0631\u0628\u0647 \u0646\u0645\u0627\u064a\u064a\u062f.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fa-IR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/#\\\/schema\\\/person\\\/fdf43ee5e6f75b62847abc89aeed6b93\",\"name\":\"\u0645\u0647\u0633\u0627 \u0645\u062d\u0645\u062f\u0632\u0627\u062f\u0647\",\"url\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/author\\\/mce1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0628\u0647\u06cc\u0646\u0647 \u0627\u0632 \u0645\u0646\u0627\u0628\u0639 | \u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u06cc \u0631\u0647\u0627 | \u0631\u0647\u0627\u0645\u06af","description":"\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u0627\u0632 \u0646\u0638\u0631 \u0645\u062d\u0627\u0633\u0628\u0627\u062a\u06cc \u0628\u0627\u0639\u062b \u0627\u06cc\u062c\u0627\u062f \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u0639\u0645\u06cc\u0642 \u062f\u0631 \u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u062f\u0627\u0631\u0648\u06cc\u06cc\u060c \u0627\u06a9\u062a\u0634\u0627\u0641 \u0627\u0646\u0631\u0698\u06cc\u060c \u062a\u0635\u0648\u06cc\u0631\u0628\u0631\u062f\u0627\u0631\u06cc \u067e\u0632\u0634\u06a9\u06cc \u0648 \u0645\u0648\u0627\u0631\u062f \u062f\u06cc\u06af\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rahaco.net\/mag\/parallel-processing-application\/","og_locale":"fa_IR","og_type":"article","og_title":"\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0628\u0647\u06cc\u0646\u0647 \u0627\u0632 \u0645\u0646\u0627\u0628\u0639 | \u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u06cc \u0631\u0647\u0627 | \u0631\u0647\u0627\u0645\u06af","og_description":"\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u0627\u0632 \u0646\u0638\u0631 \u0645\u062d\u0627\u0633\u0628\u0627\u062a\u06cc \u0628\u0627\u0639\u062b \u0627\u06cc\u062c\u0627\u062f \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u0639\u0645\u06cc\u0642 \u062f\u0631 \u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u062f\u0627\u0631\u0648\u06cc\u06cc\u060c \u0627\u06a9\u062a\u0634\u0627\u0641 \u0627\u0646\u0631\u0698\u06cc\u060c \u062a\u0635\u0648\u06cc\u0631\u0628\u0631\u062f\u0627\u0631\u06cc \u067e\u0632\u0634\u06a9\u06cc \u0648 \u0645\u0648\u0627\u0631\u062f \u062f\u06cc\u06af\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f.","og_url":"https:\/\/rahaco.net\/mag\/parallel-processing-application\/","og_site_name":"\u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u06cc \u0631\u0647\u0627 | \u0631\u0647\u0627\u0645\u06af","article_publisher":"https:\/\/www.facebook.com\/rahacompanies","article_published_time":"2023-03-11T08:30:24+00:00","article_modified_time":"2023-07-17T11:08:33+00:00","og_image":[{"width":1080,"height":686,"url":"https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/02\/\u06a9\u0627\u0631\u0628\u0631\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0645\u0648\u0627\u0632\u06cc.jpg","type":"image\/jpeg"}],"author":"\u0645\u0647\u0633\u0627 \u0645\u062d\u0645\u062f\u0632\u0627\u062f\u0647","twitter_card":"summary_large_image","twitter_creator":"@CompaniesRaha","twitter_site":"@CompaniesRaha","twitter_misc":{"\u0646\u0648\u0634\u062a\u0647 \u0634\u062f\u0647 \u062a\u0648\u0633\u0637":"\u0645\u0647\u0633\u0627 \u0645\u062d\u0645\u062f\u0632\u0627\u062f\u0647","\u0632\u0645\u0627\u0646 \u062a\u062e\u0645\u06cc\u0646\u06cc \u0645\u0637\u0627\u0644\u0639\u0647":"7 \u062f\u0642\u06cc\u0642\u0647"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rahaco.net\/mag\/parallel-processing-application\/#article","isPartOf":{"@id":"https:\/\/rahaco.net\/mag\/parallel-processing-application\/"},"author":{"name":"\u0645\u0647\u0633\u0627 \u0645\u062d\u0645\u062f\u0632\u0627\u062f\u0647","@id":"https:\/\/rahaco.net\/mag\/#\/schema\/person\/fdf43ee5e6f75b62847abc89aeed6b93"},"headline":"\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc\u061b \u0628\u0647\u062a\u0631\u06cc\u0646 \u0631\u0648\u0634 \u0628\u0631\u0627\u06cc \u0627\u0646\u062c\u0627\u0645 \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u067e\u06cc\u0686\u06cc\u062f\u0647","datePublished":"2023-03-11T08:30:24+00:00","dateModified":"2023-07-17T11:08:33+00:00","mainEntityOfPage":{"@id":"https:\/\/rahaco.net\/mag\/parallel-processing-application\/"},"wordCount":24,"commentCount":0,"image":{"@id":"https:\/\/rahaco.net\/mag\/parallel-processing-application\/#primaryimage"},"thumbnailUrl":"https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/02\/\u06a9\u0627\u0631\u0628\u0631\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0645\u0648\u0627\u0632\u06cc.jpg","keywords":["\u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc","\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc"],"articleSection":["\u0627\u062e\u0628\u0627\u0631"],"inLanguage":"fa-IR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rahaco.net\/mag\/parallel-processing-application\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rahaco.net\/mag\/parallel-processing-application\/","url":"https:\/\/rahaco.net\/mag\/parallel-processing-application\/","name":"\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u062f\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0628\u0647\u06cc\u0646\u0647 \u0627\u0632 \u0645\u0646\u0627\u0628\u0639 | \u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u06cc \u0631\u0647\u0627 | \u0631\u0647\u0627\u0645\u06af","isPartOf":{"@id":"https:\/\/rahaco.net\/mag\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rahaco.net\/mag\/parallel-processing-application\/#primaryimage"},"image":{"@id":"https:\/\/rahaco.net\/mag\/parallel-processing-application\/#primaryimage"},"thumbnailUrl":"https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/02\/\u06a9\u0627\u0631\u0628\u0631\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0645\u0648\u0627\u0632\u06cc.jpg","datePublished":"2023-03-11T08:30:24+00:00","dateModified":"2023-07-17T11:08:33+00:00","author":{"@id":"https:\/\/rahaco.net\/mag\/#\/schema\/person\/fdf43ee5e6f75b62847abc89aeed6b93"},"description":"\u06a9\u0627\u0631\u0628\u0631\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0645\u0648\u0627\u0632\u06cc \u0627\u0632 \u0646\u0638\u0631 \u0645\u062d\u0627\u0633\u0628\u0627\u062a\u06cc \u0628\u0627\u0639\u062b \u0627\u06cc\u062c\u0627\u062f \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u0639\u0645\u06cc\u0642 \u062f\u0631 \u062a\u062d\u0642\u06cc\u0642\u0627\u062a \u062f\u0627\u0631\u0648\u06cc\u06cc\u060c \u0627\u06a9\u062a\u0634\u0627\u0641 \u0627\u0646\u0631\u0698\u06cc\u060c \u062a\u0635\u0648\u06cc\u0631\u0628\u0631\u062f\u0627\u0631\u06cc \u067e\u0632\u0634\u06a9\u06cc \u0648 \u0645\u0648\u0627\u0631\u062f \u062f\u06cc\u06af\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f.","inLanguage":"fa-IR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rahaco.net\/mag\/parallel-processing-application\/"]}]},{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/rahaco.net\/mag\/parallel-processing-application\/#primaryimage","url":"https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/02\/\u06a9\u0627\u0631\u0628\u0631\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0645\u0648\u0627\u0632\u06cc.jpg","contentUrl":"https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/02\/\u06a9\u0627\u0631\u0628\u0631\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0645\u0648\u0627\u0632\u06cc.jpg","width":1080,"height":686,"caption":"\u06a9\u0627\u0631\u0628\u0631\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0645\u0648\u0627\u0632\u06cc"},{"@type":"WebSite","@id":"https:\/\/rahaco.net\/mag\/#website","url":"https:\/\/rahaco.net\/mag\/","name":"\u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u06cc \u0631\u0647\u0627 | \u0631\u0647\u0627\u0645\u06af","description":"\u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u064a \u0647\u0627\u064a \u064a\u06a9 \u0634\u0647\u0631 \u0647\u0648\u0634\u0645\u0646\u062f \u0631\u0627 \u0628\u0627 \u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u064a \u0631\u0647\u0627 \u062a\u062c\u0631\u0628\u0647 \u0646\u0645\u0627\u064a\u064a\u062f.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rahaco.net\/mag\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fa-IR"},{"@type":"Person","@id":"https:\/\/rahaco.net\/mag\/#\/schema\/person\/fdf43ee5e6f75b62847abc89aeed6b93","name":"\u0645\u0647\u0633\u0627 \u0645\u062d\u0645\u062f\u0632\u0627\u062f\u0647","url":"https:\/\/rahaco.net\/mag\/author\/mce1\/"}]}},"_links":{"self":[{"href":"https:\/\/rahaco.net\/mag\/wp-json\/wp\/v2\/posts\/12015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rahaco.net\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rahaco.net\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rahaco.net\/mag\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/rahaco.net\/mag\/wp-json\/wp\/v2\/comments?post=12015"}],"version-history":[{"count":9,"href":"https:\/\/rahaco.net\/mag\/wp-json\/wp\/v2\/posts\/12015\/revisions"}],"predecessor-version":[{"id":13517,"href":"https:\/\/rahaco.net\/mag\/wp-json\/wp\/v2\/posts\/12015\/revisions\/13517"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rahaco.net\/mag\/wp-json\/wp\/v2\/media\/12020"}],"wp:attachment":[{"href":"https:\/\/rahaco.net\/mag\/wp-json\/wp\/v2\/media?parent=12015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rahaco.net\/mag\/wp-json\/wp\/v2\/categories?post=12015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rahaco.net\/mag\/wp-json\/wp\/v2\/tags?post=12015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}