{"id":12749,"date":"2023-05-21T12:00:22","date_gmt":"2023-05-21T08:30:22","guid":{"rendered":"https:\/\/rahaco.net\/mag\/?p=12749"},"modified":"2023-05-21T14:48:40","modified_gmt":"2023-05-21T11:18:40","slug":"ipu","status":"publish","type":"post","link":"https:\/\/rahaco.net\/mag\/ipu\/","title":{"rendered":"\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0686\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u062f\u0631 \u0633\u06cc\u0633\u062a\u0645 \u067e\u0631\u062f\u0627\u0632\u0634\u06cc \u0627\u0628\u0631\u06cc \u062e\u0648\u0627\u0647\u062f \u062f\u0627\u0634\u062a\u061f"},"content":{"rendered":"<p style=\"text-align: justify;\">\u0646\u06cc\u0627\u0632 \u0628\u0647 \u0633\u06cc\u0633\u062a\u0645\u200c\u0647\u0627\u06cc \u067e\u0631\u062f\u0627\u0632\u0634\u06cc \u0633\u0631\u06cc\u0639\u200c\u062a\u0631 \u0648 \u0647\u0648\u0634\u0645\u0646\u062f\u062a\u0631 \u0647\u0645\u0647 \u0631\u0627 \u0648\u0627\u0631\u062f\u0627\u0631 \u06a9\u0631\u062f\u0647 \u06a9\u0647 \u0628\u0647 \u0646\u0633\u0644 \u062c\u062f\u06cc\u062f\u06cc \u0627\u0632 \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647\u200c\u0647\u0627 \u0631\u0648\u06cc \u0628\u06cc\u0627\u0648\u0631\u0646\u062f \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u0646\u062f \u067e\u0627\u0633\u062e\u06af\u0648\u06cc \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u067e\u0631\u062f\u0627\u0632\u0634\u06cc \u0645\u0627 \u0628\u0627\u0634\u0646\u062f. \u0627\u06cc\u0646 \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647\u200c\u0647\u0627 \u06a9\u0647 \u0628\u0647 IPU \u06cc\u0627 \u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0645\u0634\u0647\u0648\u0631 \u0647\u0633\u062a\u0646\u062f \u062f\u0631 \u0622\u06cc\u0646\u062f\u0647 \u062f\u0631 \u0647\u0631 \u0633\u06cc\u0633\u062a\u0645 \u067e\u0631\u062f\u0627\u0632\u0634\u06cc \u0627\u0628\u0631\u06cc \u0648 \u0622\u0641\u0644\u0627\u06cc\u0646 \u0645\u0648\u062c\u0648\u062f \u062e\u0648\u0627\u0647\u0646\u062f \u0628\u0648\u062f. \u0627\u06cc\u0646\u062a\u0644 \u06cc\u06a9 IPU \u0645\u0646\u062a\u0634\u0631 \u06a9\u0631\u062f\u0647 \u06a9\u0647 \u062f\u0642\u06cc\u0642\u0627 \u0634\u0628\u06cc\u0647 \u0628\u0647 SmartNIC \u0627\u0633\u062a. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647\u060c \u06cc\u0627\u062f \u062e\u0648\u0627\u0647\u06cc\u0645 \u06af\u0631\u0641\u062a \u06a9\u0647 IPU \u06cc\u0627 \u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0686\u06cc\u0633\u062a\u060c \u0686\u0647 \u06a9\u0627\u0631\u06cc \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc\u200c\u062f\u0647\u062f \u0648 \u0686\u0631\u0627 \u0627\u0647\u0645\u06cc\u062a \u062f\u0627\u0631\u062f\u061f<br \/>\n\u0627\u0631\u0627\u0626\u0647\u200c \u062f\u0647\u0646\u062f\u06af\u0627\u0646 \u062e\u062f\u0645\u0627\u062a \u0648 \u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u060c \u0633\u0631\u0645\u0627\u06cc\u0647\u200c \u06af\u0630\u0627\u0631\u06cc \u0647\u0646\u06af\u0641\u062a\u06cc \u0631\u0627 \u062f\u0631 \u0645\u0631\u0627\u06a9\u0632 \u062f\u0627\u062f\u0647 \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f \u062a\u0627 \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u06a9\u0627\u0631\u0622\u0645\u062f \u0631\u0627 \u0628\u0631\u0627\u06cc \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0647\u0627\u06cc \u0628\u0648\u0645\u06cc \u0627\u0628\u0631\u06cc \u0648 \u062e\u062f\u0645\u0627\u062a \u062e\u0631\u062f \u0627\u0631\u0627\u0626\u0647 \u062f\u0647\u0646\u062f. \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0647\u0627\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u0627\u0631\u0627\u0626\u0647 \u062f\u0647\u0646\u062f\u0647 \u0627\u06cc\u0646 \u062e\u062f\u0645\u0627\u062a \u0628\u0627\u06cc\u062f \u0628\u0647 \u0630\u062e\u06cc\u0631\u0647 \u0633\u0627\u0632\u06cc \u0628\u0627 \u0633\u0631\u0639\u062a \u0628\u0627\u0644\u0627 \u0648 \u062a\u0627\u062e\u06cc\u0631 \u06a9\u0645 \u0648 <a href=\"https:\/\/rahaco.net\/mag\/setting-up-network-infrastructure\/\">\u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0634\u0628\u06a9\u0647<\/a> \u0627\u06cc\u0645\u0646 \u062f\u0633\u062a\u0631\u0633\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f. \u0628\u0627 \u0627\u06cc\u0646 \u062d\u0627\u0644\u060c \u062e\u062f\u0645\u0627\u062a \u0632\u06cc\u0631\u0633\u0627\u062e\u062a\u06cc \u0645\u0627\u0646\u0646\u062f: \u0633\u0648\u0626\u06cc\u0686\u06cc\u0646\u06af \u0645\u062c\u0627\u0632\u06cc\u060c \u0627\u0645\u0646\u06cc\u062a \u0648 \u0630\u062e\u06cc\u0631\u0647 \u0633\u0627\u0632\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u062a\u0639\u062f\u0627\u062f \u0642\u0627\u0628\u0644 \u062a\u0648\u062c\u0647\u06cc \u0627\u0632 \u0686\u0631\u062e\u0647\u200c\u0647\u0627\u06cc CPU \u0631\u0627 \u0645\u0635\u0631\u0641 \u06a9\u0646\u0646\u062f. \u0648\u0627\u062d\u062f\u0647\u0627\u06cc \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a (IPU) \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0634\u0628\u06a9\u0647 \u0631\u0627 \u062a\u0633\u0631\u06cc\u0639 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u0648 \u0647\u0633\u062a\u0647\u200c\u0647\u0627\u06cc CPU \u0631\u0627 \u0628\u0631\u0627\u06cc \u0628\u0647\u0628\u0648\u062f \u0639\u0645\u0644\u06a9\u0631\u062f \u0628\u0631\u0646\u0627\u0645\u0647 \u0622\u0632\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-white ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0622\u0646\u0686\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0646\u0648\u0634\u062a\u0647 \u0645\u06cc\u200c\u062e\u0648\u0627\u0646\u06cc\u062f:<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"\u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/rahaco.net\/mag\/ipu\/#%D9%85%D8%B9%D8%B1%D9%81%DB%8C_IPU_%DB%8C%D8%A7_%D9%88%D8%A7%D8%AD%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D8%B2%DB%8C%D8%B1%D8%B3%D8%A7%D8%AE%D8%AA\" >\u0645\u0639\u0631\u0641\u06cc IPU \u06cc\u0627 \u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/rahaco.net\/mag\/ipu\/#%D8%B9%D9%85%D9%84%DA%A9%D8%B1%D8%AF_%D9%88%D8%A7%D8%AD%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D8%B2%DB%8C%D8%B1%D8%B3%D8%A7%D8%AE%D8%AA\" >\u0639\u0645\u0644\u06a9\u0631\u062f \u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/rahaco.net\/mag\/ipu\/#%D8%A8%D9%86%DB%8C%D8%A7%D9%86%E2%80%8C%DA%AF%D8%B0%D8%A7%D8%B1_%D9%88_%D9%85%D8%AF%DB%8C%D8%B1_%D8%B9%D8%A7%D9%85%D9%84_%D9%81%D8%B9%D9%84%DB%8C_%D8%B4%D8%B1%DA%A9%D8%AA_Graphcore\" >\u0628\u0646\u06cc\u0627\u0646\u200c\u06af\u0630\u0627\u0631 \u0648 \u0645\u062f\u06cc\u0631 \u0639\u0627\u0645\u0644 \u0641\u0639\u0644\u06cc \u0634\u0631\u06a9\u062a Graphcore<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/rahaco.net\/mag\/ipu\/#%D9%88%D8%A7%D8%AD%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D8%B2%DB%8C%D8%B1%D8%B3%D8%A7%D8%AE%D8%AA_IPU_%DA%86%DA%AF%D9%88%D9%86%D9%87_%DA%A9%D8%A7%D8%B1_%D9%85%DB%8C%E2%80%8C%DA%A9%D9%86%D8%AF%D8%9F\" >\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a IPU \u0686\u06af\u0648\u0646\u0647 \u06a9\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/rahaco.net\/mag\/ipu\/#%D9%88%DB%8C%DA%98%DA%AF%DB%8C%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%A7%D8%B5%D9%84%DB%8C_%DB%8C%DA%A9_IPU_%D9%88%D8%A7%D8%AD%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D8%B2%DB%8C%D8%B1%D8%B3%D8%A7%D8%AE%D8%AA_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\" >\u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0627\u0635\u0644\u06cc \u06cc\u06a9 IPU \u00a0\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0686\u06cc\u0633\u062a\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/rahaco.net\/mag\/ipu\/#%DA%86%D8%B1%D8%A7_IPU_%D9%88%D8%A7%D8%AD%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D8%B2%DB%8C%D8%B1%D8%B3%D8%A7%D8%AE%D8%AA_%D9%85%D9%87%D9%85_%D8%A7%D8%B3%D8%AA%D8%9F\" >\u0686\u0631\u0627 IPU\u00a0 \u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0645\u0647\u0645 \u0627\u0633\u062a\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/rahaco.net\/mag\/ipu\/#%D9%86%D8%AA%DB%8C%D8%AC%D9%87_%DA%AF%DB%8C%D8%B1%DB%8C\" >\u0646\u062a\u06cc\u062c\u0647 \u06af\u06cc\u0631\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/rahaco.net\/mag\/ipu\/#_%D8%AF%D8%A7%D9%86%D9%84%D9%88%D8%AF_PDF_%D9%85%D9%82%D8%A7%D9%84%D9%87_%D9%88%D8%A7%D8%AD%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D8%B2%DB%8C%D8%B1%D8%B3%D8%A7%D8%AE%D8%AA\" >\u00a0\u062f\u0627\u0646\u0644\u0648\u062f PDF \u0645\u0642\u0627\u0644\u0647 \u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B9%D8%B1%D9%81%DB%8C_IPU_%DB%8C%D8%A7_%D9%88%D8%A7%D8%AD%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D8%B2%DB%8C%D8%B1%D8%B3%D8%A7%D8%AE%D8%AA\"><\/span><strong>\u0645\u0639\u0631\u0641\u06cc IPU <\/strong><strong>\u06cc\u0627 \u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">\u062f\u0631 \u062d\u0627\u0644\u062a \u06a9\u0644\u06cc \u0628\u0627\u06cc\u062f \u06af\u0641\u062a \u06a9\u0647 IPU \u0633\u0627\u062e\u062a\u0627\u0631\u06cc \u0634\u0628\u06cc\u0647 \u0628\u0647 \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647\u200c\u0647\u0627\u06cc \u06af\u0631\u0627\u0641\u06cc\u06a9\u06cc \u06cc\u0627 \u0647\u0645\u0627\u0646 GPU \u062f\u0627\u0631\u0646\u062f. \u0648\u0644\u06cc \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u067e\u0631\u062f\u0627\u0632\u0634\u06cc \u0622\u0646\u200c\u0647\u0627 \u0628\u0647 \u0633\u0628\u0628 \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a\u06cc \u06a9\u0647 \u062f\u0631 \u0633\u0627\u062e\u062a\u0627\u0631 \u0627\u0631\u062a\u0628\u0627\u0637\u0627\u062a \u0648 \u0639\u0645\u0644\u06a9\u0631\u062f \u062f\u0627\u062e\u0644\u06cc \u0622\u0646 \u0647\u0627 \u0627\u06cc\u062c\u0627\u062f \u0634\u062f\u0647 \u062a\u0627 \u0633\u0647 \u0628\u0631\u0627\u0628\u0631 \u0642\u062f\u0631\u062a\u0645\u0646\u062f\u062a\u0631 \u0627\u0632 GPU \u0627\u0633\u062a. \u0647\u062f\u0641 \u0627\u0648\u0644\u06cc\u0647 \u06cc\u06a9 IPU\u00a0 \u0628\u0647 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0641\u0631\u0635\u062a \u0645\u06cc \u062f\u0647\u062f \u062a\u0627 \u0627\u0632 \u0645\u0646\u0627\u0628\u0639 \u0628\u0627 \u0631\u0627\u0647 \u062d\u0644 \u0627\u06cc\u0645\u0646\u060c \u0642\u0627\u0628\u0644 \u0628\u0631\u0646\u0627\u0645\u0647 \u0631\u06cc\u0632\u06cc \u0648 \u067e\u0627\u06cc\u062f\u0627\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u0646\u062f. \u0648 \u0628\u0627 \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0628\u06cc\u0646 \u067e\u0631\u062f\u0627\u0632\u0634 \u0648 \u0630\u062e\u06cc\u0631\u0647 \u0633\u0627\u0632\u06cc \u062a\u0639\u0627\u062f\u0644 \u0628\u0631\u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<br \/>\n\u0634\u0631\u06a9\u062a \u0645\u0627\u06cc\u06a9\u0631\u0648\u0633\u0627\u0641\u062a \u06a9\u0647 \u0628\u0627 \u062f\u0627\u0634\u062a\u0646 \u0633\u0631\u0648\u0631\u0647\u0627\u06cc Azure \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0632\u0631\u06af\u200c\u062a\u0631\u06cc\u0646 \u062e\u062f\u0645\u0627\u062a\u200c \u062f\u0647\u0646\u062f\u0647\u200c\u0647\u0627\u06cc \u0633\u0631\u0648\u06cc\u0633\u200c\u0647\u0627\u06cc \u067e\u0631\u062f\u0627\u0632\u0634 \u0627\u0628\u0631\u06cc \u062f\u0631 \u062f\u0646\u06cc\u0627\u0633\u062a. \u0627\u0639\u0644\u0627\u0645 \u06a9\u0631\u062f \u06a9\u0647 \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647\u200c\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f\u06cc \u0631\u0627 \u0628\u0647 \u0648\u0627\u062d\u062f\u0647\u0627\u06cc \u067e\u0631\u062f\u0627\u0632\u0634 \u0627\u0628\u0631\u06cc \u062e\u0648\u062f \u0627\u0636\u0627\u0641\u0647 \u06a9\u0631\u062f\u0647 \u06a9\u0647 Graphcore IPU \u0646\u0627\u0645 \u062f\u0627\u0631\u0646\u062f. \u067e\u0627\u06cc\u0647 \u0648 \u0627\u0633\u0627\u0633 \u0633\u06cc\u0633\u062a\u0645\u200c\u0647\u0627\u06cc \u0647\u0648\u0634 \u0645\u0635\u0646\u0648\u0639\u06cc \u0628\u0631 \u062a\u0635\u0645\u06cc\u0645\u200c \u06af\u06cc\u0631\u06cc \u0628\u0631 \u0627\u0633\u0627\u0633 \u0645\u0642\u0627\u06cc\u0633\u0647 \u062f\u0627\u062f\u0647\u200c\u0647\u0627 \u0627\u0633\u062a\u0648\u0627\u0631 \u0627\u0633\u062a. \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u06cc\u06a9 \u0633\u06cc\u0633\u062a\u0645 \u0628\u0631\u0627\u06cc \u0627\u062c\u0631\u0627\u06cc \u0628\u0647\u062a\u0631 \u062f\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u0647\u0648\u0634 \u0645\u0635\u0646\u0648\u0639\u06cc \u0628\u0627\u06cc\u062f \u0628\u0647 \u0639\u0645\u0644\u06a9\u0631\u062f \u0645\u0642\u0627\u06cc\u0633\u0647 \u0648 \u062a\u0635\u0645\u06cc\u0645\u200c\u06af\u06cc\u0631\u06cc \u0633\u0631\u06cc\u0639\u200c\u062a\u0631 \u0645\u062a\u06a9\u06cc \u0628\u0627\u0634\u062f. \u062f\u0631 \u0647\u0645\u06cc\u0646 \u0632\u0645\u06cc\u0646\u0647 \u0628\u0631\u0646\u0627\u0645\u0647 \u0646\u0648\u06cc\u0633\u0627\u0646 \u0647\u0648\u0634 \u0645\u0635\u0646\u0648\u0639\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647\u200c\u0647\u0627\u06cc Graphcore \u0633\u0627\u062e\u062a\u0627\u0631\u06cc \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f. \u06a9\u0647 \u0628\u0627 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0627\u0631\u0632\u0627\u0646\u062a\u0631\u06cc \u0628\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0639\u0645\u0644\u06cc\u0627\u062a \u0645\u062f \u0646\u0638\u0631 \u062e\u0648\u062f \u0628\u067e\u0631\u062f\u0627\u0632\u062f. \u0686\u0631\u0627 \u06a9\u0647 IPU \u0647\u0632\u06cc\u0646\u0647 \u062a\u0645\u0627\u0645 \u0634\u062f\u0647\u200c\u0627\u06cc \u062f\u0631 \u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647\u200c\u0647\u0627\u06cc \u062f\u06cc\u06af\u0631 \u062e\u0648\u0627\u0647\u0646\u062f \u062f\u0627\u0634\u062a \u0648 \u0647\u0645\u0627\u0646\u0637\u0648\u0631 \u06a9\u0647 \u0639\u0646\u0648\u0627\u0646 \u0634\u062f \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062a\u0627 \u0633\u0647 \u0628\u0631\u0627\u0628\u0631 \u0642\u062f\u0631\u062a\u0645\u0646\u062f\u062a\u0631 \u0628\u0627\u0634\u062f.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-12752\" src=\"https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/05\/IPU.jpg\" alt=\"IPU\" width=\"1080\" height=\"686\" srcset=\"https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/05\/IPU.jpg 1080w, https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/05\/IPU-300x191.jpg 300w, https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/05\/IPU-1024x650.jpg 1024w, https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/05\/IPU-768x488.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%B9%D9%85%D9%84%DA%A9%D8%B1%D8%AF_%D9%88%D8%A7%D8%AD%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D8%B2%DB%8C%D8%B1%D8%B3%D8%A7%D8%AE%D8%AA\"><\/span><strong>\u0639\u0645\u0644\u06a9\u0631\u062f \u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a <\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0645\u0627\u06cc\u06a9\u0631\u0648\u0633\u0627\u0641\u062a \u062f\u0631 \u062a\u0648\u0636\u06cc\u062d \u0639\u0645\u0644\u06a9\u0631\u062f Graphcore \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u062f\u0631 \u0633\u06cc\u0633\u062a\u0645\u200c\u0647\u0627\u06cc \u067e\u0631\u062f\u0627\u0632\u0634\u06cc Azure \u0639\u0646\u0648\u0627\u0646 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 IPU \u0628\u0647 \u06a9\u0627\u0631 \u0631\u0641\u062a\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0633\u06cc\u0633\u062a\u0645\u200c\u0647\u0627 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u0627\u0631\u0627\u0626\u0647 \u067e\u0631\u062f\u0627\u0632\u0634 \u0647\u0648\u0634\u0645\u0646\u062f \u0645\u0627\u0634\u06cc\u0646\u06cc \u0628\u0647 \u0642\u062f\u0631\u062a 1.6 \u067e\u062a\u0627\u0641\u0644\u0627\u067e\u0633 \u0631\u0627 \u062f\u0627\u0631\u062f. \u06a9\u0647 \u0628\u0627 \u0628\u0647 \u06a9\u0627\u0631\u200c\u06af\u06cc\u0631\u06cc \u0647\u0634\u062a \u06a9\u0627\u0631\u062a Geaphcire C2 IPU \u06a9\u0647 \u0628\u0627 \u0627\u062a\u0635\u0627\u0644 \u06a9\u0627\u0631\u062a\u200c\u0647\u0627\u06cc PCIe \u0628\u0627 \u0633\u06cc\u0633\u062a\u0645 \u0648 \u0633\u0631\u0648\u0631\u0647\u0627\u06cc \u0634\u0631\u06a9\u062a \u0627\u0631\u062a\u0628\u0627\u0637 \u0628\u0631\u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0647\u0631 \u06a9\u062f\u0627\u0645 \u0627\u0632 \u0627\u06cc\u0646 \u06a9\u0627\u0631\u062a\u200c\u0647\u0627 \u062f\u0627\u0631\u0627\u06cc \u062f\u0648 \u0648\u0627\u062d\u062f IPU \u062c\u062f\u06cc\u062f \u0647\u0633\u062a\u0646\u062f. \u06a9\u0647 \u0631\u0648\u06cc \u06cc\u06a9 \u0628\u0631\u062f \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f 4U \u0633\u0648\u0627\u0631 \u0634\u062f\u0647 \u0648 \u0627\u0631\u062a\u0628\u0627\u0637 \u0622\u0646\u200c\u0647\u0627 \u0628\u0627 \u0633\u06cc\u0633\u062a\u0645 \u0646\u06cc\u0632 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0641\u0646\u0627\u0648\u0631\u06cc \u0627\u0631\u062a\u0628\u0627\u0637\u06cc \u062c\u062f\u06cc\u062f\u06cc \u0645\u0648\u0633\u0648\u0645 \u0628\u0647 IPU-Link \u0635\u0648\u0631\u062a \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f.<br \/>\n\u0627\u06cc\u0646 \u0633\u06cc\u0633\u062a\u0645 \u062f\u0631 \u062d\u0627\u0644 \u062d\u0627\u0636\u0631 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0627\u0632 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0645\u062a\u0646 \u0628\u0627\u0632 \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0645\u0627\u0634\u06cc\u0646 TensorFlow \u0631\u0627 \u062f\u0627\u0631\u062f. \u0648 \u0642\u0631\u0627\u0631 \u0627\u0633\u062a \u062a\u0627 \u067e\u0627\u06cc\u0627\u0646 \u0633\u0627\u0644 2023 \u0642\u0627\u0628\u0644\u06cc\u062a \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0627\u0632 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u06cc\u0627\u062f\u06af\u06cc\u0631\u06cc \u0645\u0627\u0634\u06cc\u0646 \u0645\u062e\u0635\u0648\u0635 PyTorch \u0646\u06cc\u0632 \u0628\u0647 \u0622\u0646 \u0627\u0641\u0632\u0648\u062f\u0647 \u0634\u0648\u062f. \u0633\u0627\u062e\u062a \u06cc\u06a9 \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647 \u0628\u0627 \u0631\u0648\u06cc\u06a9\u0631\u062f \u062c\u062f\u06cc\u062f \u0647\u0648\u0634 \u0645\u0635\u0646\u0648\u0639\u06cc \u0646\u06cc\u0627\u0632\u0645\u0646\u062f \u06cc\u06a9 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c \u06af\u0630\u0627\u0631\u06cc \u06af\u0633\u062a\u0631\u062f\u0647 \u0627\u0633\u062a. \u06a9\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u062e\u0635\u0648\u0635 \u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc \u0628\u0632\u0631\u06af\u06cc \u062f\u0633\u062a \u0628\u0647 \u0647\u0645\u06a9\u0627\u0631\u06cc \u0628\u0627 \u06cc\u06a9\u062f\u06cc\u06af\u0631 \u0648 \u0627\u06cc\u062c\u0627\u062f \u06cc\u06a9 \u0646\u0647\u0627\u062f \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u0628\u0631\u0627\u06cc \u0633\u0627\u062e\u062a Graphcore \u0632\u062f\u0647\u200c\u0627\u0646\u062f \u06a9\u0647 \u0645\u0627\u06cc\u06a9\u0631\u0648\u0633\u0627\u0641\u062a \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u0633\u062a.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%A8%D9%86%DB%8C%D8%A7%D9%86%E2%80%8C%DA%AF%D8%B0%D8%A7%D8%B1_%D9%88_%D9%85%D8%AF%DB%8C%D8%B1_%D8%B9%D8%A7%D9%85%D9%84_%D9%81%D8%B9%D9%84%DB%8C_%D8%B4%D8%B1%DA%A9%D8%AA_Graphcore\"><\/span><strong>\u0628\u0646\u06cc\u0627\u0646\u200c\u06af\u0630\u0627\u0631 \u0648 \u0645\u062f\u06cc\u0631 \u0639\u0627\u0645\u0644 \u0641\u0639\u0644\u06cc \u0634\u0631\u06a9\u062a <\/strong><strong>Graphcore<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0646\u0627\u06cc\u062c\u0644 \u062a\u0648\u0646 \u0628\u0646\u06cc\u0627\u0646 \u06af\u0630\u0627\u0631 \u0634\u0631\u06a9\u062a Graphcore \u06af\u0641\u062a: \u062f\u0631 \u062d\u0627\u0644 \u062d\u0627\u0636\u0631 \u0628\u0633\u06cc\u0627\u0631 \u062e\u0648\u0634\u062d\u0627\u0644 \u0648 \u0645\u0641\u062a\u062e\u0631\u06cc\u0645 \u06a9\u0647 \u062a\u0648\u0627\u0646\u0633\u062a\u0647\u200c\u0627\u06cc\u0645 \u0641\u0646\u0627\u0648\u0631\u06cc \u062c\u062f\u06cc\u062f\u06cc \u0628\u0631\u0627\u06cc \u0633\u0627\u062e\u062a \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647\u200c\u0647\u0627\u06cc \u0647\u0648\u0634 \u0645\u0635\u0646\u0648\u0639\u06cc Graphcore \u0631\u0627 \u0628\u0647 \u0635\u0648\u0631\u062a \u062a\u062c\u0627\u0631\u06cc \u062f\u0631 \u0622\u0648\u0631\u062f\u0647 \u0648 \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u06af\u0631\u0648\u0647 \u0648\u0633\u06cc\u0639\u06cc \u0627\u0632 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u0642\u0631\u0627\u0631 \u062f\u0647\u06cc\u0645. \u0628\u0627 \u0646\u06af\u0627\u0647\u06cc \u0628\u0647 \u0622\u06cc\u0646\u062f\u0647 \u0648 \u0627\u0645\u06cc\u062f \u0628\u0647 \u067e\u0634\u062a\u06cc\u0628\u0627\u0646\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0627\u0632 \u0646\u0648\u0622\u0648\u0631\u0627\u0646\u06cc \u06a9\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0632\u0645\u06cc\u0646\u0647 \u06a9\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u062a\u0648\u0633\u0639\u0647 \u0639\u0638\u06cc\u0645\u06cc \u062f\u0631 \u0627\u0646\u062a\u0638\u0627\u0631 IPU \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0647\u0648\u0634 \u0645\u0627\u0634\u06cc\u0646\u06cc \u0631\u0627 \u062f\u0633\u062a\u062e\u0648\u0634 \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u0634\u06af\u0631\u0641 \u0642\u0631\u0627\u0631 \u062f\u0647\u062f. \u062a\u0627 \u0628\u0647 \u0627\u0645\u0631\u0648\u0632 \u0647\u0645\u06a9\u0627\u0631\u06cc \u06af\u0633\u062a\u0631\u062f\u0647 \u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc\u06cc \u0645\u0627\u0646\u0646\u062f: \u0645\u0627\u06cc\u06a9\u0631\u0648\u0633\u0627\u0641\u062a\u060c BMW \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u0646\u0647\u0627\u062f\u0647\u0627\u06cc\u06cc \u0645\u0627\u0646\u0646\u062f: Merian Global Investors\u060c Amadeus Capital Partners\u060cAtomico, Robert Bosch Venture Capital, Atomico \u0648 Sofina \u0628\u0627\u0639\u062b \u0634\u062f\u0647 \u06a9\u0647 \u0628\u0648\u062f\u062c\u0647 Graphcore \u0628\u0647 1.5 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062f\u0644\u0627\u0631 \u0628\u0631\u0633\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%88%D8%A7%D8%AD%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D8%B2%DB%8C%D8%B1%D8%B3%D8%A7%D8%AE%D8%AA_IPU_%DA%86%DA%AF%D9%88%D9%86%D9%87_%DA%A9%D8%A7%D8%B1_%D9%85%DB%8C%E2%80%8C%DA%A9%D9%86%D8%AF%D8%9F\"><\/span><strong>\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a <\/strong><strong>IPU<\/strong><strong> \u0686\u06af\u0648\u0646\u0647 \u06a9\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f\u061f<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">IPU \u06cc\u06a9 \u062f\u0633\u062a\u06af\u0627\u0647 \u0634\u0628\u06a9\u0647 \u0642\u0627\u0628\u0644 \u0628\u0631\u0646\u0627\u0645\u0647 \u0631\u06cc\u0632\u06cc \u0627\u0633\u062a. \u06a9\u0647 \u0628\u0647 \u0637\u0648\u0631 \u0647\u0648\u0634\u0645\u0646\u062f \u0645\u0646\u0627\u0628\u0639 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u062f\u0631 \u0633\u0637\u062d \u0633\u06cc\u0633\u062a\u0645 \u0631\u0627 \u0628\u0627 \u062a\u0633\u0631\u06cc\u0639 \u0627\u06cc\u0645\u0646 \u0622\u0646 \u0639\u0645\u0644\u06a9\u0631\u062f\u0647\u0627 \u062f\u0631 \u06cc\u06a9 \u0645\u0631\u06a9\u0632 \u062f\u0627\u062f\u0647 \u0645\u062f\u06cc\u0631\u06cc\u062a \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0628\u0647 \u0627\u067e\u0631\u0627\u062a\u0648\u0631\u0647\u0627\u06cc \u0627\u0628\u0631\u06cc \u0627\u062c\u0627\u0632\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f \u062a\u0627 \u0628\u0647 \u06cc\u06a9 \u0641\u0636\u0627\u06cc \u0630\u062e\u06cc\u0631\u0647\u200c \u0633\u0627\u0632\u06cc \u0648 \u0645\u0639\u0645\u0627\u0631\u06cc \u0634\u0628\u06a9\u0647 \u06a9\u0627\u0645\u0644\u0627 \u0645\u062c\u0627\u0632\u06cc \u062a\u0628\u062f\u06cc\u0644 \u0634\u0648\u0646\u062f. \u0648 \u062f\u0631 \u0639\u06cc\u0646 \u062d\u0627\u0644 \u062f\u0631\u062c\u0647 \u0628\u0627\u0644\u0627\u06cc\u06cc \u0627\u0632 \u0639\u0645\u0644\u06a9\u0631\u062f\u060c \u067e\u06cc\u0634\u200c\u0628\u06cc\u0646\u06cc\u200c \u067e\u0630\u06cc\u0631\u06cc \u0648 \u06a9\u0646\u062a\u0631\u0644 \u0631\u0627 \u062d\u0641\u0638 \u06a9\u0646\u0646\u062f. \u06cc\u06a9 IPU \u062f\u0627\u0631\u0627\u06cc \u0639\u0645\u0644\u06a9\u0631\u062f \u0627\u062e\u062a\u0635\u0627\u0635\u06cc \u0628\u0631\u0627\u06cc \u062a\u0633\u0631\u06cc\u0639 \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0647\u0627\u06cc \u0645\u062f\u0631\u0646 \u0627\u0633\u062a. \u06a9\u0647 \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u0639\u0645\u0627\u0631\u06cc \u0645\u0628\u062a\u0646\u06cc \u0628\u0631 \u0645\u06cc\u06a9\u0631\u0648\u0633\u0631\u0648\u06cc\u0633 \u062f\u0631 \u0645\u0631\u06a9\u0632 \u062f\u0627\u062f\u0647 \u0633\u0627\u062e\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u062f\u0631 \u0646\u062a\u06cc\u062c\u0647\u060c \u06cc\u06a9 \u0627\u0631\u0627\u0626\u0647\u200c \u062f\u0647\u0646\u062f\u0647 \u0627\u0628\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0639\u0645\u0644\u06a9\u0631\u062f\u0647\u0627\u06cc \u0632\u06cc\u0631\u0633\u0627\u062e\u062a\u06cc \u0631\u0627 \u0628\u0647\u200c \u0637\u0648\u0631 \u0627\u06cc\u0645\u0646 \u0645\u062f\u06cc\u0631\u06cc\u062a \u06a9\u0646\u062f. \u0648 \u062f\u0631 \u0639\u06cc\u0646 \u062d\u0627\u0644 \u0645\u0634\u062a\u0631\u06cc \u062e\u0648\u062f \u0631\u0627 \u0642\u0627\u062f\u0631 \u0645\u06cc\u200c\u0633\u0627\u0632\u062f \u062a\u0627 \u0639\u0645\u0644\u06a9\u0631\u062f\u0647\u0627\u06cc CPU \u0648 \u062d\u0627\u0641\u0638\u0647 \u0633\u06cc\u0633\u062a\u0645 \u0631\u0627 \u06a9\u0627\u0645\u0644\u0627 \u06a9\u0646\u062a\u0631\u0644 \u06a9\u0646\u062f.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-12754\" src=\"https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/05\/\u0648\u0627\u062d\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-IPU.jpg\" alt=\"\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 IPU\" width=\"1080\" height=\"686\" srcset=\"https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/05\/\u0648\u0627\u062d\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-IPU.jpg 1080w, https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/05\/\u0648\u0627\u062d\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-IPU-300x191.jpg 300w, https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/05\/\u0648\u0627\u062d\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-IPU-1024x650.jpg 1024w, https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/05\/\u0648\u0627\u062d\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-IPU-768x488.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%88%DB%8C%DA%98%DA%AF%DB%8C%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%A7%D8%B5%D9%84%DB%8C_%DB%8C%DA%A9_IPU_%D9%88%D8%A7%D8%AD%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D8%B2%DB%8C%D8%B1%D8%B3%D8%A7%D8%AE%D8%AA_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\"><\/span><strong>\u0648\u06cc\u0698\u06af\u06cc\u200c\u0647\u0627\u06cc \u0627\u0635\u0644\u06cc \u06cc\u06a9 <\/strong><strong>IPU<\/strong><strong> \u00a0\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0686\u06cc\u0633\u062a\u061f<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0686\u0647\u0627\u0631 \u0648\u06cc\u0698\u06af\u06cc \u0627\u0635\u0644\u06cc \u06cc\u06a9 IPU \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f:<\/p>\n<ul style=\"text-align: justify;\">\n<li>\u0634\u062a\u0627\u0628 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0628\u0633\u06cc\u0627\u0631 \u0647\u0648\u0634\u0645\u0646\u062f<\/li>\n<li>\u0627\u0645\u0646\u06cc\u062a\u060c \u06a9\u0646\u062a\u0631\u0644 \u0648 \u062c\u062f\u0627\u0633\u0627\u0632\u06cc \u062f\u0631 \u0633\u0637\u062d \u0633\u06cc\u0633\u062a\u0645<\/li>\n<li>\u0686\u0627\u0631\u0686\u0648\u0628\u200c\u0647\u0627\u06cc \u0646\u0631\u0645 \u0627\u0641\u0632\u0627\u0631\u06cc \u0631\u0627\u06cc\u062c<\/li>\n<li>\u0633\u062e\u062a \u0627\u0641\u0632\u0627\u0631 \u0648 \u0646\u0631\u0645 \u0627\u0641\u0632\u0627\u0631 \u0642\u0627\u0628\u0644 \u0628\u0631\u0646\u0627\u0645\u0647 \u0631\u06cc\u0632\u06cc\u060c \u0633\u0627\u062e\u062a\u0647 \u0634\u062f\u0647 \u0628\u0631 \u0627\u0633\u0627\u0633 \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u0645\u0634\u062a\u0631\u06cc<\/li>\n<\/ul>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%DA%86%D8%B1%D8%A7_IPU_%D9%88%D8%A7%D8%AD%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D8%B2%DB%8C%D8%B1%D8%B3%D8%A7%D8%AE%D8%AA_%D9%85%D9%87%D9%85_%D8%A7%D8%B3%D8%AA%D8%9F\"><\/span><strong>\u0686\u0631\u0627 <\/strong><strong>IPU<\/strong><strong>\u00a0 <\/strong><strong>\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a <\/strong><strong>\u0645\u0647\u0645 \u0627\u0633\u062a\u061f<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u06cc\u06a9 IPU \u0627\u06cc\u0646 \u0642\u0627\u0628\u0644\u06cc\u062a \u0631\u0627 \u062f\u0627\u0631\u062f \u06a9\u0647 \u0639\u0645\u0644\u06a9\u0631\u062f\u0647\u0627\u06cc \u0632\u06cc\u0631\u0633\u0627\u062e\u062a\u060c \u0627\u0632 \u062c\u0645\u0644\u0647 \u0645\u062c\u0627\u0632\u06cc \u0633\u0627\u0632\u06cc \u0630\u062e\u06cc\u0631\u0647 \u0633\u0627\u0632\u06cc\u060c \u0645\u062c\u0627\u0632\u06cc \u0633\u0627\u0632\u06cc \u0634\u0628\u06a9\u0647 \u0648 \u0627\u0645\u0646\u06cc\u062a \u0631\u0627 \u0628\u0627 \u0634\u062a\u0627\u0628 \u062f\u0647\u0646\u062f\u0647\u200c\u0647\u0627\u06cc \u067e\u0631\u0648\u062a\u06a9\u0644 \u0627\u062e\u062a\u0635\u0627\u0635\u06cc \u0631\u0627 \u0628\u0627 \u0633\u0631\u0639\u062a \u0628\u06cc\u0634\u062a\u0631\u06cc \u0627\u0646\u062c\u0627\u0645 \u062f\u0627\u062f. \u062f\u0631 \u0645\u0642\u06cc\u0627\u0633 \u0628\u0632\u0631\u06af\u200c\u062a\u0631\u060c \u0645\u0631\u0627\u06a9\u0632 \u062f\u0627\u062f\u0647 \u062f\u0631 \u062d\u0627\u0644 \u062a\u06a9\u0627\u0645\u0644 \u0628\u0647 \u06cc\u06a9 \u0645\u0639\u0645\u0627\u0631\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u062c\u062f\u06cc\u062f \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u0646\u062f \u06a9\u0647 \u062f\u0631 \u0622\u0646 \u0633\u06cc\u0633\u062a\u0645\u200c\u0647\u0627\u06cc \u0645\u062d\u0627\u0633\u0628\u0627\u062a\u06cc \u062a\u0648\u0632\u06cc\u0639\u200c \u0634\u062f\u0647 \u062f\u0631 \u0645\u0642\u06cc\u0627\u0633 \u0628\u0632\u0631\u06af \u0628\u0647 \u200c\u0635\u0648\u0631\u062a \u06cc\u06a9\u067e\u0627\u0631\u0686\u0647 \u0628\u0647\u200c \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u067e\u0644\u062a\u0641\u0631\u0645 \u0648\u0627\u062d\u062f \u0628\u0647 \u0647\u0645 \u0645\u062a\u0635\u0644 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f.<\/p>\n<p style=\"text-align: justify;\">\u0627\u06cc\u0646 \u0628\u0647 \u062d\u0644 \u0686\u0627\u0644\u0634\u200c\u0647\u0627\u06cc \u0627\u0645\u0631\u0648\u0632\u06cc\u060c \u062c\u0631\u06cc\u0627\u0646 \u062f\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u0645\u062a\u0631\u0627\u06a9\u0645 \u0648 \u0627\u0645\u0646\u06cc\u062a \u067e\u0644\u062a\u0641\u0631\u0645 \u0646\u0627\u0633\u0627\u0632\u06af\u0627\u0631 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0639\u0645\u0627\u0631\u06cc \u062c\u062f\u06cc\u062f\u060c \u0633\u0647 \u062f\u0633\u062a\u0647 \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u0648\u062c\u0648\u062f \u062e\u0648\u0627\u0647\u062f \u062f\u0627\u0634\u062a:\u00a0CPU \u0628\u0631\u0627\u06cc \u0645\u062d\u0627\u0633\u0628\u0627\u062a \u0628\u0627 \u0647\u062f\u0641 \u0639\u0645\u0648\u0645\u06cc\u060c XPU (\u0648\u0627\u062d\u062f \u0645\u062a\u0642\u0627\u0628\u0644 \u067e\u0644\u062a\u0641\u0631\u0645) \u0628\u0631\u0627\u06cc \u0634\u062a\u0627\u0628 \u0648\u06cc\u0698\u0647 \u0628\u0631\u0646\u0627\u0645\u0647 \u06cc\u0627 \u062d\u062c\u0645 \u06a9\u0627\u0631\u06cc \u062e\u0627\u0635\u060c \u0648 IPU \u0628\u0631\u0627\u06cc \u0634\u062a\u0627\u0628 \u0632\u06cc\u0631 \u0633\u0627\u062e\u062a.<\/p>\n<p style=\"text-align: justify;\">\u0647\u0631 \u0633\u0647 \u062f\u0633\u062a\u0647 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0634\u0628\u06a9\u0647\u200c\u0647\u0627\u06cc \u0642\u0627\u0628\u0644 \u0628\u0631\u0646\u0627\u0645\u0647 \u0631\u06cc\u0632\u06cc \u0628\u0631\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u0648\u062b\u0631 \u0627\u0632 \u0645\u0646\u0627\u0628\u0639 \u0645\u0631\u06a9\u0632 \u062f\u0627\u062f\u0647 \u0628\u0647 \u0647\u0645 \u0645\u062a\u0635\u0644 \u062e\u0648\u0627\u0647\u0646\u062f \u0634\u062f. \u0645\u0631\u0627\u06a9\u0632 \u062f\u0627\u062f\u0647 \u062f\u0631 \u062d\u0627\u0644 \u062a\u06a9\u0627\u0645\u0644 \u0628\u0647 \u06cc\u06a9 \u0645\u0639\u0645\u0627\u0631\u06cc \u0647\u0648\u0634\u0645\u0646\u062f \u062c\u062f\u06cc\u062f \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u0646\u062f. \u06a9\u0647 \u062f\u0631 \u0622\u0646 \u0633\u06cc\u0633\u062a\u0645\u200c\u0647\u0627\u06cc \u0645\u062d\u0627\u0633\u0628\u0627\u062a\u06cc \u062a\u0648\u0632\u06cc\u0639 \u0634\u062f\u0647 \u062f\u0631 \u0645\u0642\u06cc\u0627\u0633 \u0628\u0632\u0631\u06af \u0628\u0647 \u0635\u0648\u0631\u062a \u06cc\u06a9\u067e\u0627\u0631\u0686\u0647 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u067e\u0644\u062a\u0641\u0631\u0645 \u0648\u0627\u062d\u062f \u0628\u0647 \u0647\u0645 \u0645\u062a\u0635\u0644 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%86%D8%AA%DB%8C%D8%AC%D9%87_%DA%AF%DB%8C%D8%B1%DB%8C\"><\/span><strong>\u0646\u062a\u06cc\u062c\u0647 \u06af\u06cc\u0631\u06cc <\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0645\u0632\u0627\u06cc\u0627\u06cc \u06a9\u0644\u06cc\u062f\u06cc \u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a Intel \u0645\u0627\u0646\u0646\u062f \u0627\u0641\u0632\u0627\u06cc\u0634 \u0627\u0645\u0646\u06cc\u062a \u0627\u0632 \u0637\u0631\u06cc\u0642 \u062c\u062f\u0627\u0633\u0627\u0632\u06cc \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0647\u0627 \u0627\u0632 \u062e\u062f\u0645\u0627\u062a \u0627\u0631\u0627\u0626\u0647\u200c \u062f\u0647\u0646\u062f\u0647\u060c \u062a\u062e\u0644\u06cc\u0647 \u0648\u0638\u0627\u06cc\u0641 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0628\u0631\u0627\u06cc \u0628\u0647\u0628\u0648\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0648 \u0639\u0645\u0644\u06a9\u0631\u062f CPU\u060c \u0648 \u0641\u0639\u0627\u0644 \u06a9\u0631\u062f\u0646 \u0641\u0636\u0627\u06cc \u0630\u062e\u06cc\u0631\u0647\u200c\u0633\u0627\u0632\u06cc \u0645\u062c\u0627\u0632\u06cc \u0628\u0631\u0627\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u0627\u0646\u0639\u0637\u0627\u0641\u200c \u067e\u0630\u06cc\u0631\u06cc \u0645\u0631\u06a9\u0632 \u062f\u0627\u062f\u0647. \u0634\u0631\u06a9\u062a Graphcore \u062a\u0648\u0627\u0646\u0633\u062a\u0647 \u062a\u0627 \u0628\u0647 \u0627\u0645\u0631\u0648\u0632 \u0645\u0628\u0627\u0644\u063a \u0645\u0648\u0631\u062f \u062a\u0648\u062c\u0647\u06cc \u0631\u0627 \u0646\u06cc\u0632 \u0627\u0632 \u0627\u0641\u0631\u0627\u062f \u0645\u0631\u062a\u0628\u0637 \u0628\u0627 \u062d\u0648\u0632\u0647 \u067e\u0631\u062f\u0627\u0632\u0634\u06cc \u0647\u0648\u0634 \u0645\u0635\u0646\u0648\u0639\u06cc \u0645\u0627\u0646\u0646\u062f: \u062f\u0645\u06cc\u0633 \u062d\u0633\u0627\u0628\u06cc\u0633\u060c \u0628\u0646\u06cc\u0627\u0646\u200c\u06af\u0630\u0627\u0631 \u0628\u062e\u0634 DeepMind \u0634\u0631\u06a9\u062a \u06af\u0648\u06af\u0644 \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0698\u0648\u0628\u06cc\u0646 \u0642\u0647\u0631\u0645\u0627\u0646\u06cc\u060c \u06cc\u06a9\u06cc \u0627\u0632 \u062f\u0627\u0646\u0634\u0645\u0646\u062f\u0627\u0646 \u0628\u0631\u062c\u0633\u062a\u0647\u200c\u0627\u06cc \u06a9\u0647 \u062f\u0631 \u062d\u0627\u0644 \u062d\u0627\u0636\u0631 \u062f\u0631 Uber \u0645\u0634\u063a\u0648\u0644 \u0641\u0639\u0627\u0644\u06cc\u062a \u0627\u0633\u062a \u06a9\u0633\u0628 \u06a9\u0646\u062f \u06a9\u0647 \u0645\u0633\u0644\u0645\u0627 \u0628\u0647 \u062a\u0648\u0633\u0639\u0647 \u0628\u06cc\u0634\u062a\u0631 \u0622\u0646 \u062e\u0648\u0627\u0647\u062f \u0627\u0646\u062c\u0627\u0645\u06cc\u062f.<\/p>\n<h3 style=\"text-align: center;\"><span class=\"ez-toc-section\" id=\"_%D8%AF%D8%A7%D9%86%D9%84%D9%88%D8%AF_PDF_%D9%85%D9%82%D8%A7%D9%84%D9%87_%D9%88%D8%A7%D8%AD%D8%AF_%D9%BE%D8%B1%D8%AF%D8%A7%D8%B2%D8%B4_%D8%B2%DB%8C%D8%B1%D8%B3%D8%A7%D8%AE%D8%AA\"><\/span><span style=\"color: #ff6600;\"><strong>\u00a0\u062f\u0627\u0646\u0644\u0648\u062f PDF \u0645\u0642\u0627\u0644\u0647 \u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;12749&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;0&quot;,&quot;greet&quot;:&quot;\u062b\u0628\u062a \u0627\u0645\u062a\u06cc\u0627\u0632 post&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 \u0627\u0645\u062a\u06cc\u0627\u0632)&quot;,&quot;size&quot;:&quot;22&quot;,&quot;title&quot;:&quot;\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0686\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u062f\u0631 \u0633\u06cc\u0633\u062a\u0645 \u067e\u0631\u062f\u0627\u0632\u0634\u06cc \u0627\u0628\u0631\u06cc \u062e\u0648\u0627\u0647\u062f \u062f\u0627\u0634\u062a\u061f&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-left: 0px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-left: 0px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-left: 0px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-left: 0px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-left: 0px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-left: 0px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 0px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 0px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 0px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 0px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 17.6px;\">\n            <span class=\"kksr-muted\">\u062b\u0628\u062a \u0627\u0645\u062a\u06cc\u0627\u0632 post<\/span>\n    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0646\u06cc\u0627\u0632 \u0628\u0647 \u0633\u06cc\u0633\u062a\u0645\u200c\u0647\u0627\u06cc \u067e\u0631\u062f\u0627\u0632\u0634\u06cc \u0633\u0631\u06cc\u0639\u200c\u062a\u0631 \u0648 \u0647\u0648\u0634\u0645\u0646\u062f\u062a\u0631 \u0647\u0645\u0647 \u0631\u0627 \u0648\u0627\u0631\u062f\u0627\u0631 \u06a9\u0631\u062f\u0647 \u06a9\u0647 \u0628\u0647 \u0646\u0633\u0644 \u062c\u062f\u06cc\u062f\u06cc \u0627\u0632 \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647\u200c\u0647\u0627 \u0631\u0648\u06cc \u0628\u06cc\u0627\u0648\u0631\u0646\u062f \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u0646\u062f \u067e\u0627\u0633\u062e\u06af\u0648\u06cc \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u067e\u0631\u062f\u0627\u0632\u0634\u06cc \u0645\u0627 \u0628\u0627\u0634\u0646\u062f. \u0627\u06cc\u0646&#8230;<\/p>\n","protected":false},"author":9,"featured_media":12751,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[100],"tags":[1817],"class_list":["post-12749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-ipu"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0648 \u0627\u0631\u062a\u0628\u0627\u0637 \u0622\u0646 \u0628\u0627 \u0633\u0627\u06cc\u0631 \u0633\u0631\u0648\u06cc\u0633 \u0647\u0627\u06cc \u0627\u0628\u0631\u06cc | \u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u06cc \u0631\u0647\u0627 | \u0631\u0647\u0627\u0645\u06af<\/title>\n<meta name=\"description\" content=\"\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0633\u0627\u062e\u062a\u0627\u0631\u06cc \u0634\u0628\u06cc\u0647 \u0628\u0647 \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647\u200c\u0647\u0627\u06cc \u06af\u0631\u0627\u0641\u06cc\u06a9\u06cc \u06cc\u0627 \u0647\u0645\u0627\u0646 GPU \u062f\u0627\u0631\u0646\u062f. \u0648\u0644\u06cc \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u067e\u0631\u062f\u0627\u0632\u0634\u06cc \u0622\u0646\u200c\u0647\u0627 \u062a\u0627 \u0633\u0647 \u0628\u0631\u0627\u0628\u0631 \u0642\u062f\u0631\u062a\u0645\u0646\u062f\u062a\u0631 \u0627\u0632 GPU \u0627\u0633\u062a.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rahaco.net\/mag\/ipu\/\" \/>\n<meta property=\"og:locale\" content=\"fa_IR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0648 \u0627\u0631\u062a\u0628\u0627\u0637 \u0622\u0646 \u0628\u0627 \u0633\u0627\u06cc\u0631 \u0633\u0631\u0648\u06cc\u0633 \u0647\u0627\u06cc \u0627\u0628\u0631\u06cc | \u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u06cc \u0631\u0647\u0627 | \u0631\u0647\u0627\u0645\u06af\" \/>\n<meta property=\"og:description\" content=\"\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0633\u0627\u062e\u062a\u0627\u0631\u06cc \u0634\u0628\u06cc\u0647 \u0628\u0647 \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647\u200c\u0647\u0627\u06cc \u06af\u0631\u0627\u0641\u06cc\u06a9\u06cc \u06cc\u0627 \u0647\u0645\u0627\u0646 GPU \u062f\u0627\u0631\u0646\u062f. \u0648\u0644\u06cc \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u067e\u0631\u062f\u0627\u0632\u0634\u06cc \u0622\u0646\u200c\u0647\u0627 \u062a\u0627 \u0633\u0647 \u0628\u0631\u0627\u0628\u0631 \u0642\u062f\u0631\u062a\u0645\u0646\u062f\u062a\u0631 \u0627\u0632 GPU \u0627\u0633\u062a.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rahaco.net\/mag\/ipu\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u06cc \u0631\u0647\u0627 | \u0631\u0647\u0627\u0645\u06af\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rahacompanies\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-21T08:30:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-21T11:18:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/05\/\u0648\u0627\u062d\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0632\u06cc\u0631\u0633\u0627\u062e\u062a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"686\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0645\u0647\u0633\u0627 \u0645\u062d\u0645\u062f\u0632\u0627\u062f\u0647\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CompaniesRaha\" \/>\n<meta name=\"twitter:site\" content=\"@CompaniesRaha\" \/>\n<meta name=\"twitter:label1\" content=\"\u0646\u0648\u0634\u062a\u0647 \u0634\u062f\u0647 \u062a\u0648\u0633\u0637\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0645\u0647\u0633\u0627 \u0645\u062d\u0645\u062f\u0632\u0627\u062f\u0647\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0632\u0645\u0627\u0646 \u062a\u062e\u0645\u06cc\u0646\u06cc \u0645\u0637\u0627\u0644\u0639\u0647\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 \u062f\u0642\u06cc\u0642\u0647\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/ipu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/ipu\\\/\"},\"author\":{\"name\":\"\u0645\u0647\u0633\u0627 \u0645\u062d\u0645\u062f\u0632\u0627\u062f\u0647\",\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/#\\\/schema\\\/person\\\/fdf43ee5e6f75b62847abc89aeed6b93\"},\"headline\":\"\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0686\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u062f\u0631 \u0633\u06cc\u0633\u062a\u0645 \u067e\u0631\u062f\u0627\u0632\u0634\u06cc \u0627\u0628\u0631\u06cc \u062e\u0648\u0627\u0647\u062f \u062f\u0627\u0634\u062a\u061f\",\"datePublished\":\"2023-05-21T08:30:22+00:00\",\"dateModified\":\"2023-05-21T11:18:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/ipu\\\/\"},\"wordCount\":66,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/ipu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/\u0648\u0627\u062d\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0632\u06cc\u0631\u0633\u0627\u062e\u062a.jpg\",\"keywords\":[\"IPU\"],\"articleSection\":[\"\u0627\u062e\u0628\u0627\u0631\"],\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/rahaco.net\\\/mag\\\/ipu\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/ipu\\\/\",\"url\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/ipu\\\/\",\"name\":\"\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0648 \u0627\u0631\u062a\u0628\u0627\u0637 \u0622\u0646 \u0628\u0627 \u0633\u0627\u06cc\u0631 \u0633\u0631\u0648\u06cc\u0633 \u0647\u0627\u06cc \u0627\u0628\u0631\u06cc | \u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u06cc \u0631\u0647\u0627 | \u0631\u0647\u0627\u0645\u06af\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/ipu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/ipu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/\u0648\u0627\u062d\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0632\u06cc\u0631\u0633\u0627\u062e\u062a.jpg\",\"datePublished\":\"2023-05-21T08:30:22+00:00\",\"dateModified\":\"2023-05-21T11:18:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/#\\\/schema\\\/person\\\/fdf43ee5e6f75b62847abc89aeed6b93\"},\"description\":\"\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0633\u0627\u062e\u062a\u0627\u0631\u06cc \u0634\u0628\u06cc\u0647 \u0628\u0647 \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647\u200c\u0647\u0627\u06cc \u06af\u0631\u0627\u0641\u06cc\u06a9\u06cc \u06cc\u0627 \u0647\u0645\u0627\u0646 GPU \u062f\u0627\u0631\u0646\u062f. \u0648\u0644\u06cc \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u067e\u0631\u062f\u0627\u0632\u0634\u06cc \u0622\u0646\u200c\u0647\u0627 \u062a\u0627 \u0633\u0647 \u0628\u0631\u0627\u0628\u0631 \u0642\u062f\u0631\u062a\u0645\u0646\u062f\u062a\u0631 \u0627\u0632 GPU \u0627\u0633\u062a.\",\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rahaco.net\\\/mag\\\/ipu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/ipu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/\u0648\u0627\u062d\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0632\u06cc\u0631\u0633\u0627\u062e\u062a.jpg\",\"contentUrl\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/\u0648\u0627\u062d\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0632\u06cc\u0631\u0633\u0627\u062e\u062a.jpg\",\"width\":1080,\"height\":686,\"caption\":\"\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/#website\",\"url\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/\",\"name\":\"\u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u06cc \u0631\u0647\u0627 | \u0631\u0647\u0627\u0645\u06af\",\"description\":\"\u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u064a \u0647\u0627\u064a \u064a\u06a9 \u0634\u0647\u0631 \u0647\u0648\u0634\u0645\u0646\u062f \u0631\u0627 \u0628\u0627 \u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u064a \u0631\u0647\u0627 \u062a\u062c\u0631\u0628\u0647 \u0646\u0645\u0627\u064a\u064a\u062f.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fa-IR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/#\\\/schema\\\/person\\\/fdf43ee5e6f75b62847abc89aeed6b93\",\"name\":\"\u0645\u0647\u0633\u0627 \u0645\u062d\u0645\u062f\u0632\u0627\u062f\u0647\",\"url\":\"https:\\\/\\\/rahaco.net\\\/mag\\\/author\\\/mce1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0648 \u0627\u0631\u062a\u0628\u0627\u0637 \u0622\u0646 \u0628\u0627 \u0633\u0627\u06cc\u0631 \u0633\u0631\u0648\u06cc\u0633 \u0647\u0627\u06cc \u0627\u0628\u0631\u06cc | \u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u06cc \u0631\u0647\u0627 | \u0631\u0647\u0627\u0645\u06af","description":"\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0633\u0627\u062e\u062a\u0627\u0631\u06cc \u0634\u0628\u06cc\u0647 \u0628\u0647 \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647\u200c\u0647\u0627\u06cc \u06af\u0631\u0627\u0641\u06cc\u06a9\u06cc \u06cc\u0627 \u0647\u0645\u0627\u0646 GPU \u062f\u0627\u0631\u0646\u062f. \u0648\u0644\u06cc \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u067e\u0631\u062f\u0627\u0632\u0634\u06cc \u0622\u0646\u200c\u0647\u0627 \u062a\u0627 \u0633\u0647 \u0628\u0631\u0627\u0628\u0631 \u0642\u062f\u0631\u062a\u0645\u0646\u062f\u062a\u0631 \u0627\u0632 GPU \u0627\u0633\u062a.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rahaco.net\/mag\/ipu\/","og_locale":"fa_IR","og_type":"article","og_title":"\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0648 \u0627\u0631\u062a\u0628\u0627\u0637 \u0622\u0646 \u0628\u0627 \u0633\u0627\u06cc\u0631 \u0633\u0631\u0648\u06cc\u0633 \u0647\u0627\u06cc \u0627\u0628\u0631\u06cc | \u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u06cc \u0631\u0647\u0627 | \u0631\u0647\u0627\u0645\u06af","og_description":"\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0633\u0627\u062e\u062a\u0627\u0631\u06cc \u0634\u0628\u06cc\u0647 \u0628\u0647 \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647\u200c\u0647\u0627\u06cc \u06af\u0631\u0627\u0641\u06cc\u06a9\u06cc \u06cc\u0627 \u0647\u0645\u0627\u0646 GPU \u062f\u0627\u0631\u0646\u062f. \u0648\u0644\u06cc \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u067e\u0631\u062f\u0627\u0632\u0634\u06cc \u0622\u0646\u200c\u0647\u0627 \u062a\u0627 \u0633\u0647 \u0628\u0631\u0627\u0628\u0631 \u0642\u062f\u0631\u062a\u0645\u0646\u062f\u062a\u0631 \u0627\u0632 GPU \u0627\u0633\u062a.","og_url":"https:\/\/rahaco.net\/mag\/ipu\/","og_site_name":"\u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u06cc \u0631\u0647\u0627 | \u0631\u0647\u0627\u0645\u06af","article_publisher":"https:\/\/www.facebook.com\/rahacompanies","article_published_time":"2023-05-21T08:30:22+00:00","article_modified_time":"2023-05-21T11:18:40+00:00","og_image":[{"width":1080,"height":686,"url":"https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/05\/\u0648\u0627\u062d\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0632\u06cc\u0631\u0633\u0627\u062e\u062a.jpg","type":"image\/jpeg"}],"author":"\u0645\u0647\u0633\u0627 \u0645\u062d\u0645\u062f\u0632\u0627\u062f\u0647","twitter_card":"summary_large_image","twitter_creator":"@CompaniesRaha","twitter_site":"@CompaniesRaha","twitter_misc":{"\u0646\u0648\u0634\u062a\u0647 \u0634\u062f\u0647 \u062a\u0648\u0633\u0637":"\u0645\u0647\u0633\u0627 \u0645\u062d\u0645\u062f\u0632\u0627\u062f\u0647","\u0632\u0645\u0627\u0646 \u062a\u062e\u0645\u06cc\u0646\u06cc \u0645\u0637\u0627\u0644\u0639\u0647":"7 \u062f\u0642\u06cc\u0642\u0647"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rahaco.net\/mag\/ipu\/#article","isPartOf":{"@id":"https:\/\/rahaco.net\/mag\/ipu\/"},"author":{"name":"\u0645\u0647\u0633\u0627 \u0645\u062d\u0645\u062f\u0632\u0627\u062f\u0647","@id":"https:\/\/rahaco.net\/mag\/#\/schema\/person\/fdf43ee5e6f75b62847abc89aeed6b93"},"headline":"\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0686\u0647 \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u062f\u0631 \u0633\u06cc\u0633\u062a\u0645 \u067e\u0631\u062f\u0627\u0632\u0634\u06cc \u0627\u0628\u0631\u06cc \u062e\u0648\u0627\u0647\u062f \u062f\u0627\u0634\u062a\u061f","datePublished":"2023-05-21T08:30:22+00:00","dateModified":"2023-05-21T11:18:40+00:00","mainEntityOfPage":{"@id":"https:\/\/rahaco.net\/mag\/ipu\/"},"wordCount":66,"commentCount":0,"image":{"@id":"https:\/\/rahaco.net\/mag\/ipu\/#primaryimage"},"thumbnailUrl":"https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/05\/\u0648\u0627\u062d\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0632\u06cc\u0631\u0633\u0627\u062e\u062a.jpg","keywords":["IPU"],"articleSection":["\u0627\u062e\u0628\u0627\u0631"],"inLanguage":"fa-IR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rahaco.net\/mag\/ipu\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rahaco.net\/mag\/ipu\/","url":"https:\/\/rahaco.net\/mag\/ipu\/","name":"\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0648 \u0627\u0631\u062a\u0628\u0627\u0637 \u0622\u0646 \u0628\u0627 \u0633\u0627\u06cc\u0631 \u0633\u0631\u0648\u06cc\u0633 \u0647\u0627\u06cc \u0627\u0628\u0631\u06cc | \u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u06cc \u0631\u0647\u0627 | \u0631\u0647\u0627\u0645\u06af","isPartOf":{"@id":"https:\/\/rahaco.net\/mag\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rahaco.net\/mag\/ipu\/#primaryimage"},"image":{"@id":"https:\/\/rahaco.net\/mag\/ipu\/#primaryimage"},"thumbnailUrl":"https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/05\/\u0648\u0627\u062d\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0632\u06cc\u0631\u0633\u0627\u062e\u062a.jpg","datePublished":"2023-05-21T08:30:22+00:00","dateModified":"2023-05-21T11:18:40+00:00","author":{"@id":"https:\/\/rahaco.net\/mag\/#\/schema\/person\/fdf43ee5e6f75b62847abc89aeed6b93"},"description":"\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a \u0633\u0627\u062e\u062a\u0627\u0631\u06cc \u0634\u0628\u06cc\u0647 \u0628\u0647 \u067e\u0631\u062f\u0627\u0632\u0646\u062f\u0647\u200c\u0647\u0627\u06cc \u06af\u0631\u0627\u0641\u06cc\u06a9\u06cc \u06cc\u0627 \u0647\u0645\u0627\u0646 GPU \u062f\u0627\u0631\u0646\u062f. \u0648\u0644\u06cc \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u067e\u0631\u062f\u0627\u0632\u0634\u06cc \u0622\u0646\u200c\u0647\u0627 \u062a\u0627 \u0633\u0647 \u0628\u0631\u0627\u0628\u0631 \u0642\u062f\u0631\u062a\u0645\u0646\u062f\u062a\u0631 \u0627\u0632 GPU \u0627\u0633\u062a.","inLanguage":"fa-IR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rahaco.net\/mag\/ipu\/"]}]},{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/rahaco.net\/mag\/ipu\/#primaryimage","url":"https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/05\/\u0648\u0627\u062d\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0632\u06cc\u0631\u0633\u0627\u062e\u062a.jpg","contentUrl":"https:\/\/rahaco.net\/mag\/wp-content\/uploads\/2023\/05\/\u0648\u0627\u062d\u062f-\u067e\u0631\u062f\u0627\u0632\u0634-\u0632\u06cc\u0631\u0633\u0627\u062e\u062a.jpg","width":1080,"height":686,"caption":"\u0648\u0627\u062d\u062f \u067e\u0631\u062f\u0627\u0632\u0634 \u0632\u06cc\u0631\u0633\u0627\u062e\u062a"},{"@type":"WebSite","@id":"https:\/\/rahaco.net\/mag\/#website","url":"https:\/\/rahaco.net\/mag\/","name":"\u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u06cc \u0631\u0647\u0627 | \u0631\u0647\u0627\u0645\u06af","description":"\u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u064a \u0647\u0627\u064a \u064a\u06a9 \u0634\u0647\u0631 \u0647\u0648\u0634\u0645\u0646\u062f \u0631\u0627 \u0628\u0627 \u0645\u062c\u0644\u0647 \u062e\u0628\u0631\u064a \u0631\u0647\u0627 \u062a\u062c\u0631\u0628\u0647 \u0646\u0645\u0627\u064a\u064a\u062f.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rahaco.net\/mag\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fa-IR"},{"@type":"Person","@id":"https:\/\/rahaco.net\/mag\/#\/schema\/person\/fdf43ee5e6f75b62847abc89aeed6b93","name":"\u0645\u0647\u0633\u0627 \u0645\u062d\u0645\u062f\u0632\u0627\u062f\u0647","url":"https:\/\/rahaco.net\/mag\/author\/mce1\/"}]}},"_links":{"self":[{"href":"https:\/\/rahaco.net\/mag\/wp-json\/wp\/v2\/posts\/12749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rahaco.net\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rahaco.net\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rahaco.net\/mag\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/rahaco.net\/mag\/wp-json\/wp\/v2\/comments?post=12749"}],"version-history":[{"count":5,"href":"https:\/\/rahaco.net\/mag\/wp-json\/wp\/v2\/posts\/12749\/revisions"}],"predecessor-version":[{"id":12757,"href":"https:\/\/rahaco.net\/mag\/wp-json\/wp\/v2\/posts\/12749\/revisions\/12757"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rahaco.net\/mag\/wp-json\/wp\/v2\/media\/12751"}],"wp:attachment":[{"href":"https:\/\/rahaco.net\/mag\/wp-json\/wp\/v2\/media?parent=12749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rahaco.net\/mag\/wp-json\/wp\/v2\/categories?post=12749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rahaco.net\/mag\/wp-json\/wp\/v2\/tags?post=12749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}